{"id":67926,"date":"2025-12-19T09:33:30","date_gmt":"2025-12-19T12:33:30","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=67926"},"modified":"2025-12-19T11:27:59","modified_gmt":"2025-12-19T14:27:59","slug":"region-nucleo-cosecha-record-trigo","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/","title":{"rendered":"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos"},"content":{"rendered":"<p data-start=\"683\" data-end=\"901\">La <strong data-start=\"732\" data-end=\"760\">campa\u00f1a de trigo 2025\/26<\/strong> en la <strong data-start=\"767\" data-end=\"784\">regi\u00f3n n\u00facleo<\/strong> entra en su tramo final y confirma un <span style=\"color: #0000ff;\" data-darkreader-inline-color=\"\"><a style=\"color: #0000ff;\" href=\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-eleva-cosecha-de-trigo-2025-26-a-record-de-277-mi-ton\/\" data-darkreader-inline-color=\"\"><strong data-start=\"823\" data-end=\"843\">resultado r\u00e9cord<\/strong><\/a><\/span>, seg\u00fan inform\u00f3 la <strong data-start=\"862\" data-end=\"900\">Bolsa de Comercio de Rosario (BCR)<\/strong>.<\/p>\n<p data-start=\"903\" data-end=\"1073\">A la fecha, el <strong data-start=\"918\" data-end=\"951\">98% del \u00e1rea ya fue cosechada<\/strong>, consolidando una <strong data-start=\"970\" data-end=\"1029\">producci\u00f3n total estimada en 10,4 millones de toneladas<\/strong>, el mayor volumen hist\u00f3rico para la regi\u00f3n.<\/p>\n<h2 data-start=\"1075\" data-end=\"1104\"><strong data-start=\"1078\" data-end=\"1104\">Rindes sin precedentes<\/strong><\/h2>\n<p data-start=\"1106\" data-end=\"1234\">El <strong data-start=\"1109\" data-end=\"1136\">rinde promedio regional<\/strong> se ubica en <strong data-start=\"1149\" data-end=\"1186\">60 quintales por hect\u00e1rea (qq\/ha)<\/strong>, con desempe\u00f1os excepcionales en algunas zonas.<\/p>\n<p data-start=\"1236\" data-end=\"1381\">En <strong data-start=\"1239\" data-end=\"1256\">General Pinto<\/strong>, se registraron <strong data-start=\"1273\" data-end=\"1309\">lotes que superaron los 80 qq\/ha<\/strong>, reflejando el excelente comportamiento del cultivo durante la campa\u00f1a.<\/p>\n<h2 data-start=\"1383\" data-end=\"1420\"><strong data-start=\"1386\" data-end=\"1420\">Calidad y perspectivas finales<\/strong><\/h2>\n<p data-start=\"1422\" data-end=\"1603\">De acuerdo con el relevamiento, resta recolectar <strong data-start=\"1471\" data-end=\"1520\">menos del 20% del \u00e1rea en el norte bonaerense<\/strong>, donde las recientes <strong data-start=\"1542\" data-end=\"1569\">ventanas de buen tiempo<\/strong> permitieron acelerar las labores.<\/p>\n<p data-start=\"1605\" data-end=\"1838\">Si bien la <strong data-start=\"1616\" data-end=\"1636\">calidad proteica<\/strong> fue el aspecto m\u00e1s d\u00e9bil de la temporada, los especialistas destacan que el <strong data-start=\"1713\" data-end=\"1766\">potencial productivo alcanz\u00f3 niveles nunca vistos<\/strong> en la regi\u00f3n, con un <strong data-start=\"1788\" data-end=\"1837\">peso hectol\u00edtrico dentro de rangos aceptables<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La campa\u00f1a de trigo 2025\/26 en la regi\u00f3n n\u00facleo entra en su tramo final y confirma un resultado r\u00e9cord, seg\u00fan inform\u00f3 la Bolsa de Comercio de Rosario (BCR). A la fecha, el 98% del \u00e1rea ya fue cosechada, consolidando una producci\u00f3n total estimada en 10,4 millones de toneladas, el mayor volumen hist\u00f3rico para la regi\u00f3n. [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":67927,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[416,267],"tags":[796,128],"commodity":[49],"class_list":["post-67926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enfasis","category-agronegocio-es","tag-region-nucleo","tag-trigo","commodity-trigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos - SAFRAS &amp; Mercado<\/title>\n<meta name=\"description\" content=\"La regi\u00f3n n\u00facleo consolida una cosecha r\u00e9cord de trigo 2025\/26 con rindes promedio de 60 qq\/ha y una producci\u00f3n estimada en 10,4 Mt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"La regi\u00f3n n\u00facleo consolida una cosecha r\u00e9cord de trigo 2025\/26 con rindes promedio de 60 qq\/ha y una producci\u00f3n estimada en 10,4 Mt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-19T12:33:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T14:27:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Horacio Vera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Horacio Vera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/\"},\"author\":{\"name\":\"Horacio Vera\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\"},\"headline\":\"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos\",\"datePublished\":\"2025-12-19T12:33:30+00:00\",\"dateModified\":\"2025-12-19T14:27:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/\"},\"wordCount\":187,\"commentCount\":293,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg\",\"keywords\":[\"regi\u00f3n n\u00facleo\",\"Trigo\"],\"articleSection\":[\"\u00c9nfasis\",\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/\",\"url\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/\",\"name\":\"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg\",\"datePublished\":\"2025-12-19T12:33:30+00:00\",\"dateModified\":\"2025-12-19T14:27:59+00:00\",\"description\":\"La regi\u00f3n n\u00facleo consolida una cosecha r\u00e9cord de trigo 2025\/26 con rindes promedio de 60 qq\/ha y una producci\u00f3n estimada en 10,4 Mt.\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Instituto Nacional de Tecnolog\u00eda Agropecuaria \u2013 inta.gob.ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\",\"name\":\"Horacio Vera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"caption\":\"Horacio Vera\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_horacio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos - SAFRAS &amp; Mercado","description":"La regi\u00f3n n\u00facleo consolida una cosecha r\u00e9cord de trigo 2025\/26 con rindes promedio de 60 qq\/ha y una producci\u00f3n estimada en 10,4 Mt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/","og_locale":"es_ES","og_type":"article","og_title":"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos - SAFRAS &amp; Mercado","og_description":"La regi\u00f3n n\u00facleo consolida una cosecha r\u00e9cord de trigo 2025\/26 con rindes promedio de 60 qq\/ha y una producci\u00f3n estimada en 10,4 Mt.","og_url":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-12-19T12:33:30+00:00","article_modified_time":"2025-12-19T14:27:59+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg","type":"image\/jpeg"}],"author":"Horacio Vera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Horacio Vera","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/"},"author":{"name":"Horacio Vera","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747"},"headline":"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos","datePublished":"2025-12-19T12:33:30+00:00","dateModified":"2025-12-19T14:27:59+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/"},"wordCount":187,"commentCount":293,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg","keywords":["regi\u00f3n n\u00facleo","Trigo"],"articleSection":["\u00c9nfasis","Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/","url":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/","name":"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg","datePublished":"2025-12-19T12:33:30+00:00","dateModified":"2025-12-19T14:27:59+00:00","description":"La regi\u00f3n n\u00facleo consolida una cosecha r\u00e9cord de trigo 2025\/26 con rindes promedio de 60 qq\/ha y una producci\u00f3n estimada en 10,4 Mt.","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/trigo5.jpg","width":1280,"height":853,"caption":"Instituto Nacional de Tecnolog\u00eda Agropecuaria \u2013 inta.gob.ar"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/region-nucleo-cosecha-record-trigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Regi\u00f3n n\u00facleo confirma cosecha r\u00e9cord de trigo con rindes hist\u00f3ricos"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747","name":"Horacio Vera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","caption":"Horacio Vera"},"url":"https:\/\/safras.com.br\/es\/author\/sf_horacio\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=67926"}],"version-history":[{"count":3,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67926\/revisions"}],"predecessor-version":[{"id":67938,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67926\/revisions\/67938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/67927"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=67926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=67926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=67926"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=67926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}