{"id":67811,"date":"2025-12-12T14:12:40","date_gmt":"2025-12-12T17:12:40","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=67811"},"modified":"2025-12-12T14:12:40","modified_gmt":"2025-12-12T17:12:40","slug":"inflacion-argentina-2026-proyeccion-bbva","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/","title":{"rendered":"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026"},"content":{"rendered":"<p data-start=\"1795\" data-end=\"2087\"><strong data-start=\"1839\" data-end=\"1856\">BBVA Research<\/strong> proyecta que, si bien la <strong data-start=\"1882\" data-end=\"1924\">recomposici\u00f3n de los precios regulados<\/strong> continuar\u00e1 durante 2026, la <strong data-start=\"1953\" data-end=\"2012\"><span style=\"color: #0000ff;\" data-darkreader-inline-color=\"\"><a style=\"color: #0000ff;\" href=\"https:\/\/safras.com.br\/es\/argentina-rem-bcra-inflacion-proyecciones-2025\/\" data-darkreader-inline-color=\"\">inflaci\u00f3n en Argentina<\/a><\/span> mantendr\u00e1 un sendero descendente<\/strong>, en l\u00ednea con la din\u00e1mica desinflacionaria observada en los \u00faltimos meses.<\/p>\n<h2 data-start=\"2089\" data-end=\"2112\">Inflaci\u00f3n reciente<\/h2>\n<p data-start=\"2113\" data-end=\"2326\">En noviembre, la inflaci\u00f3n mensual alcanz\u00f3 el <strong data-start=\"2159\" data-end=\"2167\">2,5%<\/strong>, con una variaci\u00f3n <strong data-start=\"2187\" data-end=\"2211\">interanual del 31,4%<\/strong>, superando las estimaciones de consenso del mercado y marcando el <strong data-start=\"2278\" data-end=\"2325\">registro m\u00e1s alto de los \u00faltimos seis meses<\/strong>.<\/p>\n<p data-start=\"2328\" data-end=\"2531\">El principal factor detr\u00e1s de la aceleraci\u00f3n fue el <strong data-start=\"2380\" data-end=\"2427\">aumento del 6,2% en los precios de la carne<\/strong>, que tuvo una incidencia relevante sobre la <strong data-start=\"2472\" data-end=\"2492\">inflaci\u00f3n n\u00facleo<\/strong>, la cual se ubic\u00f3 en <strong data-start=\"2514\" data-end=\"2530\">2,6% mensual<\/strong>.<\/p>\n<h2 data-start=\"2533\" data-end=\"2549\">Componentes<\/h2>\n<p data-start=\"2550\" data-end=\"2670\">Adem\u00e1s del impacto de la carne, BBVA destac\u00f3 que los <strong data-start=\"2603\" data-end=\"2624\">precios regulados<\/strong> aceleraron su ritmo, impulsados por subas en:<\/p>\n<ul data-start=\"2672\" data-end=\"2726\">\n<li data-start=\"2672\" data-end=\"2688\">\n<p data-start=\"2674\" data-end=\"2688\"><strong data-start=\"2674\" data-end=\"2686\">Vivienda<\/strong><\/p>\n<\/li>\n<li data-start=\"2689\" data-end=\"2709\">\n<p data-start=\"2691\" data-end=\"2709\"><strong data-start=\"2691\" data-end=\"2707\">Electricidad<\/strong><\/p>\n<\/li>\n<li data-start=\"2710\" data-end=\"2726\">\n<p data-start=\"2712\" data-end=\"2726\"><strong data-start=\"2712\" data-end=\"2726\">Transporte<\/strong><\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2728\" data-end=\"2892\">La inflaci\u00f3n n\u00facleo, con un avance del <strong data-start=\"2767\" data-end=\"2775\">2,6%<\/strong>, alcanz\u00f3 su <strong data-start=\"2788\" data-end=\"2817\">nivel m\u00e1s alto desde mayo<\/strong>, aunque el informe se\u00f1ala que el efecto de la carne ser\u00eda <strong data-start=\"2876\" data-end=\"2891\">transitorio<\/strong>.<\/p>\n<h2 data-start=\"2894\" data-end=\"2915\">Perspectiva 2026<\/h2>\n<p data-start=\"2916\" data-end=\"3150\">\u201cA pesar de que la recomposici\u00f3n de regulados seguir\u00e1 presente en los pr\u00f3ximos meses, proyectamos que la <strong data-start=\"3021\" data-end=\"3106\">tendencia general de la econom\u00eda hacia la desinflaci\u00f3n continuar\u00e1 vigente en 2026<\/strong>\u201d, concluye el informe de <strong data-start=\"3132\" data-end=\"3149\">BBVA Research<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BBVA Research proyecta que, si bien la recomposici\u00f3n de los precios regulados continuar\u00e1 durante 2026, la inflaci\u00f3n en Argentina mantendr\u00e1 un sendero descendente, en l\u00ednea con la din\u00e1mica desinflacionaria observada en los \u00faltimos meses. Inflaci\u00f3n reciente En noviembre, la inflaci\u00f3n mensual alcanz\u00f3 el 2,5%, con una variaci\u00f3n interanual del 31,4%, superando las estimaciones de consenso [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":67812,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[444],"tags":[],"commodity":[],"class_list":["post-67811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026 - SAFRAS &amp; Mercado<\/title>\n<meta name=\"description\" content=\"BBVA proyecta que la inflaci\u00f3n en Argentina seguir\u00e1 bajando en 2026, pese a la recomposici\u00f3n de precios regulados y subas puntuales como la carne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026 - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"BBVA proyecta que la inflaci\u00f3n en Argentina seguir\u00e1 bajando en 2026, pese a la recomposici\u00f3n de precios regulados y subas puntuales como la carne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T17:12:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"580\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Horacio Vera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Horacio Vera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/\"},\"author\":{\"name\":\"Horacio Vera\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\"},\"headline\":\"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026\",\"datePublished\":\"2025-12-12T17:12:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/\"},\"wordCount\":213,\"commentCount\":463,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg\",\"articleSection\":[\"Noticias Financieras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/\",\"url\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/\",\"name\":\"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026 - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg\",\"datePublished\":\"2025-12-12T17:12:40+00:00\",\"description\":\"BBVA proyecta que la inflaci\u00f3n en Argentina seguir\u00e1 bajando en 2026, pese a la recomposici\u00f3n de precios regulados y subas puntuales como la carne.\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg\",\"width\":580,\"height\":330,\"caption\":\"inflacion3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\",\"name\":\"Horacio Vera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"caption\":\"Horacio Vera\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_horacio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026 - SAFRAS &amp; Mercado","description":"BBVA proyecta que la inflaci\u00f3n en Argentina seguir\u00e1 bajando en 2026, pese a la recomposici\u00f3n de precios regulados y subas puntuales como la carne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/","og_locale":"es_ES","og_type":"article","og_title":"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026 - SAFRAS &amp; Mercado","og_description":"BBVA proyecta que la inflaci\u00f3n en Argentina seguir\u00e1 bajando en 2026, pese a la recomposici\u00f3n de precios regulados y subas puntuales como la carne.","og_url":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-12-12T17:12:40+00:00","og_image":[{"width":580,"height":330,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg","type":"image\/jpeg"}],"author":"Horacio Vera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Horacio Vera","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/"},"author":{"name":"Horacio Vera","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747"},"headline":"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026","datePublished":"2025-12-12T17:12:40+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/"},"wordCount":213,"commentCount":463,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg","articleSection":["Noticias Financieras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/","url":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/","name":"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026 - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg","datePublished":"2025-12-12T17:12:40+00:00","description":"BBVA proyecta que la inflaci\u00f3n en Argentina seguir\u00e1 bajando en 2026, pese a la recomposici\u00f3n de precios regulados y subas puntuales como la carne.","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/inflacion3-1.jpeg","width":580,"height":330,"caption":"inflacion3"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/inflacion-argentina-2026-proyeccion-bbva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"BBVA prev\u00e9 inflaci\u00f3n a la baja en Argentina en 2026"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747","name":"Horacio Vera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","caption":"Horacio Vera"},"url":"https:\/\/safras.com.br\/es\/author\/sf_horacio\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=67811"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67811\/revisions"}],"predecessor-version":[{"id":67813,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67811\/revisions\/67813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/67812"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=67811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=67811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=67811"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=67811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}