{"id":67766,"date":"2025-12-10T11:25:53","date_gmt":"2025-12-10T14:25:53","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=67766"},"modified":"2025-12-10T11:25:53","modified_gmt":"2025-12-10T14:25:53","slug":"canje-bonos-2029-bonar","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/","title":{"rendered":"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG"},"content":{"rendered":"<p data-start=\"2050\" data-end=\"2371\">De acuerdo con un an\u00e1lisis de <strong data-start=\"2124\" data-end=\"2139\">BTG Pactual<\/strong>, un <strong data-start=\"2144\" data-end=\"2188\"><span style=\"color: #0000ff;\" data-darkreader-inline-color=\"\"><a style=\"color: #0000ff;\" href=\"https:\/\/safras.com.br\/es\/argentina-regreso-mercado-capitales\/\" data-darkreader-inline-color=\"\">canje de los bonos soberanos 2029<\/a><\/span> y 2030<\/strong> por un nuevo t\u00edtulo bullet con vencimiento en <strong data-start=\"2235\" data-end=\"2243\">2033<\/strong> permitir\u00eda <strong data-start=\"2255\" data-end=\"2300\">aliviar las amortizaciones de corto plazo<\/strong>, reduciendo las necesidades inmediatas de financiamiento del Gobierno.<\/p>\n<p data-start=\"2373\" data-end=\"2576\">Sin embargo, el banco advierte que el nuevo bono deber\u00eda ofrecer un <strong data-start=\"2441\" data-end=\"2459\">cup\u00f3n m\u00e1s alto<\/strong>, lo que implicar\u00eda <strong data-start=\"2479\" data-end=\"2509\">mayores pagos de intereses<\/strong> y, por lo tanto, <strong data-start=\"2527\" data-end=\"2575\">presi\u00f3n adicional sobre las cuentas fiscales<\/strong>.<\/p>\n<h2 data-start=\"2578\" data-end=\"2610\">Impacto financiero estimado<\/h2>\n<p data-start=\"2611\" data-end=\"2641\">Seg\u00fan las estimaciones de BTG:<\/p>\n<ul data-start=\"2643\" data-end=\"2852\">\n<li data-start=\"2643\" data-end=\"2691\">\n<p data-start=\"2645\" data-end=\"2691\">Un bono <strong data-start=\"2653\" data-end=\"2661\">2033<\/strong> con cup\u00f3n cercano al <strong data-start=\"2683\" data-end=\"2689\">7%<\/strong><\/p>\n<\/li>\n<li data-start=\"2692\" data-end=\"2774\">\n<p data-start=\"2694\" data-end=\"2774\">Reducir\u00eda los <strong data-start=\"2708\" data-end=\"2746\">servicios totales de deuda en 2027<\/strong> en <strong data-start=\"2750\" data-end=\"2772\">US$ 3.600 millones<\/strong><\/p>\n<\/li>\n<li data-start=\"2775\" data-end=\"2852\">\n<p data-start=\"2777\" data-end=\"2852\">Pero aumentar\u00eda los <strong data-start=\"2797\" data-end=\"2810\">intereses<\/strong> en aproximadamente <strong data-start=\"2830\" data-end=\"2852\">US$ 1.700 millones<\/strong><\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2854\" data-end=\"3055\">El informe remarca que, si bien el alivio de corto plazo es relevante, la <span style=\"color: #0000ff;\" data-darkreader-inline-color=\"\"><a style=\"color: #0000ff;\" href=\"https:\/\/safras.com.br\/es\/acumulacion-de-reservas-llevaria-el-dolar-al-techo-de-la-banda-dice-ceo-de-wise-capital\/\" data-darkreader-inline-color=\"\"><strong data-start=\"2928\" data-end=\"2971\">acumulaci\u00f3n de reservas internacionales<\/strong><\/a><\/span> sigue siendo el elemento clave para que los <strong data-start=\"3016\" data-end=\"3054\">spreads de deuda contin\u00faen bajando<\/strong>.<\/p>\n<h2 data-start=\"3057\" data-end=\"3085\">Estrategia del Gobierno<\/h2>\n<p data-start=\"3086\" data-end=\"3239\">El equipo econ\u00f3mico eval\u00faa diversas herramientas de <strong data-start=\"3138\" data-end=\"3159\">manejo de pasivos<\/strong> para reducir vencimientos inmediatos, dado que Argentina debe afrontar en 2026:<\/p>\n<ul data-start=\"3241\" data-end=\"3370\">\n<li data-start=\"3241\" data-end=\"3307\">\n<p data-start=\"3243\" data-end=\"3307\"><strong data-start=\"3243\" data-end=\"3266\">US$ 20.000 millones<\/strong> en pagos de deuda en moneda extranjera<\/p>\n<\/li>\n<li data-start=\"3308\" data-end=\"3370\">\n<p data-start=\"3310\" data-end=\"3370\">De los cuales <strong data-start=\"3324\" data-end=\"3346\">US$ 8.500 millones<\/strong> corresponden a bonistas<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"3372\" data-end=\"3507\">Entre las alternativas en estudio se encuentra precisamente un <strong data-start=\"3435\" data-end=\"3469\">canje de los bonos 2029 y 2030<\/strong> por un instrumento de mayor duraci\u00f3n.<\/p>\n<p data-start=\"2576\" data-end=\"2709\">\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo con un an\u00e1lisis de BTG Pactual, un canje de los bonos soberanos 2029 y 2030 por un nuevo t\u00edtulo bullet con vencimiento en 2033 permitir\u00eda aliviar las amortizaciones de corto plazo, reduciendo las necesidades inmediatas de financiamiento del Gobierno. Sin embargo, el banco advierte que el nuevo bono deber\u00eda ofrecer un cup\u00f3n m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":67767,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[444],"tags":[728,446,738],"commodity":[],"class_list":["post-67766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras","tag-bonar","tag-btg","tag-canje"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG - SAFRAS &amp; Mercado<\/title>\n<meta name=\"description\" content=\"BTG se\u00f1ala que un canje de bonos 2029\/2030 por un t\u00edtulo 2033 reducir\u00eda amortizaciones de corto plazo, aunque aumentar\u00eda los intereses y la presi\u00f3n fiscal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"BTG se\u00f1ala que un canje de bonos 2029\/2030 por un t\u00edtulo 2033 reducir\u00eda amortizaciones de corto plazo, aunque aumentar\u00eda los intereses y la presi\u00f3n fiscal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-10T14:25:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1618\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Horacio Vera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Horacio Vera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/\"},\"author\":{\"name\":\"Horacio Vera\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\"},\"headline\":\"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG\",\"datePublished\":\"2025-12-10T14:25:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/\"},\"wordCount\":226,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg\",\"keywords\":[\"BONAR\",\"BTG\",\"canje\"],\"articleSection\":[\"Noticias Financieras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/\",\"url\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/\",\"name\":\"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg\",\"datePublished\":\"2025-12-10T14:25:53+00:00\",\"description\":\"BTG se\u00f1ala que un canje de bonos 2029\/2030 por un t\u00edtulo 2033 reducir\u00eda amortizaciones de corto plazo, aunque aumentar\u00eda los intereses y la presi\u00f3n fiscal.\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg\",\"width\":1618,\"height\":1080,\"caption\":\"Ministerio de Econom\u00eda evaluando canje de bonos 2029 2030 para reducir vencimientos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\",\"name\":\"Horacio Vera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"caption\":\"Horacio Vera\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_horacio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG - SAFRAS &amp; Mercado","description":"BTG se\u00f1ala que un canje de bonos 2029\/2030 por un t\u00edtulo 2033 reducir\u00eda amortizaciones de corto plazo, aunque aumentar\u00eda los intereses y la presi\u00f3n fiscal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/","og_locale":"es_ES","og_type":"article","og_title":"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG - SAFRAS &amp; Mercado","og_description":"BTG se\u00f1ala que un canje de bonos 2029\/2030 por un t\u00edtulo 2033 reducir\u00eda amortizaciones de corto plazo, aunque aumentar\u00eda los intereses y la presi\u00f3n fiscal.","og_url":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-12-10T14:25:53+00:00","og_image":[{"width":1618,"height":1080,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg","type":"image\/jpeg"}],"author":"Horacio Vera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Horacio Vera","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/"},"author":{"name":"Horacio Vera","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747"},"headline":"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG","datePublished":"2025-12-10T14:25:53+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/"},"wordCount":226,"commentCount":3,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg","keywords":["BONAR","BTG","canje"],"articleSection":["Noticias Financieras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/","url":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/","name":"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg","datePublished":"2025-12-10T14:25:53+00:00","description":"BTG se\u00f1ala que un canje de bonos 2029\/2030 por un t\u00edtulo 2033 reducir\u00eda amortizaciones de corto plazo, aunque aumentar\u00eda los intereses y la presi\u00f3n fiscal.","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/12\/min-de-economia2.jpg","width":1618,"height":1080,"caption":"Ministerio de Econom\u00eda evaluando canje de bonos 2029 2030 para reducir vencimientos"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/canje-bonos-2029-bonar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Canje de bonos 2029\/2030 aliviar\u00eda vencimientos de corto plazo pero elevar\u00eda intereses, seg\u00fan BTG"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747","name":"Horacio Vera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","caption":"Horacio Vera"},"url":"https:\/\/safras.com.br\/es\/author\/sf_horacio\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=67766"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67766\/revisions"}],"predecessor-version":[{"id":67768,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67766\/revisions\/67768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/67767"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=67766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=67766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=67766"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=67766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}