{"id":67703,"date":"2025-12-02T17:04:44","date_gmt":"2025-12-02T20:04:44","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=67703"},"modified":"2025-12-02T17:04:44","modified_gmt":"2025-12-02T20:04:44","slug":"banco-nacion-calificacion-esg2-fix-sostenibilidad-2025","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/","title":{"rendered":"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad"},"content":{"rendered":"<p data-start=\"737\" data-end=\"1003\">El <strong data-start=\"783\" data-end=\"799\">Banco Naci\u00f3n<\/strong> recibi\u00f3 la <strong data-start=\"811\" data-end=\"838\">calificaci\u00f3n ESG2 (arg)<\/strong> \u2013\u201cMuy Altos Est\u00e1ndares\u201d\u2013 otorgada por <strong data-start=\"877\" data-end=\"888\">FIX SCR<\/strong>, destacando su desempe\u00f1o en <strong data-start=\"917\" data-end=\"945\">sostenibilidad ambiental<\/strong>, <strong data-start=\"947\" data-end=\"973\">responsabilidad social<\/strong> y <strong data-start=\"976\" data-end=\"1000\">gobierno corporativo<\/strong>.<\/p>\n<p data-start=\"1005\" data-end=\"1143\">El reconocimiento se enmarca en el <strong data-start=\"1040\" data-end=\"1070\">Plan Estrat\u00e9gico 2024\u20132027<\/strong>, que prioriza pr\u00e1cticas sostenibles y mayor transparencia institucional.<\/p>\n<h2 data-start=\"1145\" data-end=\"1161\">Importancia<\/h2>\n<p data-start=\"1162\" data-end=\"1435\">Con esta evaluaci\u00f3n, la entidad se posiciona como una de las <strong data-start=\"1223\" data-end=\"1269\">pocas instituciones financieras argentinas<\/strong> en alcanzar dicha categor\u00eda, reforzando su papel central dentro del sistema financiero y su capacidad para <strong data-start=\"1377\" data-end=\"1409\">articular pol\u00edticas p\u00fablicas<\/strong> junto al Estado Nacional.<\/p>\n<h2 data-start=\"1437\" data-end=\"1452\">Evaluaci\u00f3n<\/h2>\n<p data-start=\"1453\" data-end=\"1489\">El informe de <strong data-start=\"1467\" data-end=\"1478\">FIX SCR<\/strong> resalta:<\/p>\n<ul data-start=\"1490\" data-end=\"1693\">\n<li data-start=\"1490\" data-end=\"1548\">\n<p data-start=\"1492\" data-end=\"1548\">La gesti\u00f3n del <strong data-start=\"1507\" data-end=\"1536\">impacto ambiental directo<\/strong> del Banco<\/p>\n<\/li>\n<li data-start=\"1549\" data-end=\"1631\">\n<p data-start=\"1551\" data-end=\"1631\">Su estructura robusta de <strong data-start=\"1576\" data-end=\"1587\">control<\/strong>, <strong data-start=\"1589\" data-end=\"1602\">auditor\u00eda<\/strong> y <strong data-start=\"1605\" data-end=\"1629\">gobierno corporativo<\/strong><\/p>\n<\/li>\n<li data-start=\"1632\" data-end=\"1693\">\n<p data-start=\"1634\" data-end=\"1693\">Avances en <strong data-start=\"1645\" data-end=\"1662\">transparencia<\/strong> y est\u00e1ndares institucionales<\/p>\n<\/li>\n<\/ul>\n<h2 data-start=\"1695\" data-end=\"1726\">Calificaciones crediticias<\/h2>\n<p data-start=\"1727\" data-end=\"1819\">Adem\u00e1s del puntaje ESG, FIX SCR confirm\u00f3 la <strong data-start=\"1771\" data-end=\"1795\">fortaleza crediticia<\/strong> del Banco Naci\u00f3n con:<\/p>\n<ul data-start=\"1820\" data-end=\"1915\">\n<li data-start=\"1820\" data-end=\"1877\">\n<p data-start=\"1822\" data-end=\"1877\"><strong data-start=\"1822\" data-end=\"1855\">AAA (arg) Perspectiva Estable<\/strong> para el largo plazo<\/p>\n<\/li>\n<li data-start=\"1878\" data-end=\"1915\">\n<p data-start=\"1880\" data-end=\"1915\"><strong data-start=\"1880\" data-end=\"1893\">A1+ (arg)<\/strong> para el corto plazo<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El Banco Naci\u00f3n recibi\u00f3 la calificaci\u00f3n ESG2 (arg) \u2013\u201cMuy Altos Est\u00e1ndares\u201d\u2013 otorgada por FIX SCR, destacando su desempe\u00f1o en sostenibilidad ambiental, responsabilidad social y gobierno corporativo. El reconocimiento se enmarca en el Plan Estrat\u00e9gico 2024\u20132027, que prioriza pr\u00e1cticas sostenibles y mayor transparencia institucional. Importancia Con esta evaluaci\u00f3n, la entidad se posiciona como una de las [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":66171,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[444],"tags":[571,710,711],"commodity":[],"class_list":["post-67703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras","tag-banco-nacion","tag-calificacion-esg","tag-sostenibilidad-financiera"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad - SAFRAS &amp; Mercado<\/title>\n<meta name=\"description\" content=\"El Banco Naci\u00f3n obtuvo la calificaci\u00f3n ESG2 por sus altos est\u00e1ndares ambientales, sociales y de gobierno corporativo, seg\u00fan FIX SCR.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"El Banco Naci\u00f3n obtuvo la calificaci\u00f3n ESG2 por sus altos est\u00e1ndares ambientales, sociales y de gobierno corporativo, seg\u00fan FIX SCR.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-02T20:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"geronimo kener\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"geronimo kener\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/\"},\"author\":{\"name\":\"geronimo kener\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3c7009f94cf442d9df6f2cd1eedd0bfd\"},\"headline\":\"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad\",\"datePublished\":\"2025-12-02T20:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/\"},\"wordCount\":170,\"commentCount\":459,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg\",\"keywords\":[\"Banco Naci\u00f3n\",\"calificaci\u00f3n ESG\",\"sostenibilidad financiera\"],\"articleSection\":[\"Noticias Financieras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/\",\"url\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/\",\"name\":\"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg\",\"datePublished\":\"2025-12-02T20:04:44+00:00\",\"description\":\"El Banco Naci\u00f3n obtuvo la calificaci\u00f3n ESG2 por sus altos est\u00e1ndares ambientales, sociales y de gobierno corporativo, seg\u00fan FIX SCR.\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Banco Naci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3c7009f94cf442d9df6f2cd1eedd0bfd\",\"name\":\"geronimo kener\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/97803e93b95c46f5640aea59976da81aba4ba2ddb9a9f119122d0a068646612f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/97803e93b95c46f5640aea59976da81aba4ba2ddb9a9f119122d0a068646612f?s=96&d=mm&r=g\",\"caption\":\"geronimo kener\"},\"sameAs\":[\"http:\/\/safras.com.br\/es\"],\"url\":\"https:\/\/safras.com.br\/es\/author\/geronimo-kener\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad - SAFRAS &amp; Mercado","description":"El Banco Naci\u00f3n obtuvo la calificaci\u00f3n ESG2 por sus altos est\u00e1ndares ambientales, sociales y de gobierno corporativo, seg\u00fan FIX SCR.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad - SAFRAS &amp; Mercado","og_description":"El Banco Naci\u00f3n obtuvo la calificaci\u00f3n ESG2 por sus altos est\u00e1ndares ambientales, sociales y de gobierno corporativo, seg\u00fan FIX SCR.","og_url":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-12-02T20:04:44+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg","type":"image\/jpeg"}],"author":"geronimo kener","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"geronimo kener","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/"},"author":{"name":"geronimo kener","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3c7009f94cf442d9df6f2cd1eedd0bfd"},"headline":"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad","datePublished":"2025-12-02T20:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/"},"wordCount":170,"commentCount":459,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg","keywords":["Banco Naci\u00f3n","calificaci\u00f3n ESG","sostenibilidad financiera"],"articleSection":["Noticias Financieras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/","url":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/","name":"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg","datePublished":"2025-12-02T20:04:44+00:00","description":"El Banco Naci\u00f3n obtuvo la calificaci\u00f3n ESG2 por sus altos est\u00e1ndares ambientales, sociales y de gobierno corporativo, seg\u00fan FIX SCR.","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/07\/Banco-Nacion-scaled.jpg","width":2560,"height":1707,"caption":"Banco Naci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/banco-nacion-calificacion-esg2-fix-sostenibilidad-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Banco Naci\u00f3n obtiene calificaci\u00f3n ESG2 por altos est\u00e1ndares de sostenibilidad"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3c7009f94cf442d9df6f2cd1eedd0bfd","name":"geronimo kener","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/97803e93b95c46f5640aea59976da81aba4ba2ddb9a9f119122d0a068646612f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97803e93b95c46f5640aea59976da81aba4ba2ddb9a9f119122d0a068646612f?s=96&d=mm&r=g","caption":"geronimo kener"},"sameAs":["http:\/\/safras.com.br\/es"],"url":"https:\/\/safras.com.br\/es\/author\/geronimo-kener\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=67703"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67703\/revisions"}],"predecessor-version":[{"id":67704,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67703\/revisions\/67704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/66171"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=67703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=67703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=67703"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=67703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}