{"id":67620,"date":"2025-11-26T12:40:10","date_gmt":"2025-11-26T15:40:10","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=67620"},"modified":"2025-11-26T12:40:10","modified_gmt":"2025-11-26T15:40:10","slug":"camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/","title":{"rendered":"C\u00e1mara advierte que falta ganado en Argentina y que productores est\u00e1n reteniendo animales"},"content":{"rendered":"<p data-start=\"907\" data-end=\"1193\"><a href=\"https:\/\/safras.com.br\/es\/gobierno-argentino-deroga-prohibicion-de-exportar-ganado-vacuno-en-pie-para-faena\/\"><span style=\"color: #0000ff;\"><em>La falta de ganado en Argentina<\/em><\/span> <\/a>es cada vez m\u00e1s evidente, seg\u00fan la <strong data-start=\"1022\" data-end=\"1079\">C\u00e1mara Argentina de Matarifes y Abastecedores (CAMYA)<\/strong>, que viene alertando sobre la suba del precio de la carne y la menor disponibilidad de hacienda lista para faena.<\/p>\n<h2 data-start=\"1195\" data-end=\"1248\">Retenci\u00f3n de animales y menor oferta de hacienda<\/h2>\n<p data-start=\"1249\" data-end=\"1529\">De acuerdo con <strong data-start=\"1264\" data-end=\"1281\">Sergio Pedace<\/strong>, vicepresidente de CAMYA, los exportadores se encuentran sin novillo disponible y est\u00e1n utilizando <strong data-start=\"1381\" data-end=\"1414\">novillitos gordos para recr\u00eda<\/strong>, una pr\u00e1ctica que <strong data-start=\"1433\" data-end=\"1472\">prolonga los tiempos de terminaci\u00f3n<\/strong> y reduce la cantidad de animales listos para el mercado.<\/p>\n<p data-start=\"1531\" data-end=\"1839\">Pedace se\u00f1al\u00f3 adem\u00e1s que los <strong data-start=\"1560\" data-end=\"1605\">productores est\u00e1n reteniendo m\u00e1s animales<\/strong>. Seg\u00fan explic\u00f3, hoy es m\u00e1s rentable <strong data-start=\"1642\" data-end=\"1669\">criar un novillo pesado<\/strong> que vender un ternero, mientras que muchas vacas que antes sal\u00edan como flacas ahora se <strong data-start=\"1757\" data-end=\"1795\">engordan para venderse como gordas<\/strong>, lo que tambi\u00e9n limita la oferta inmediata.<\/p>\n<h2 data-start=\"1841\" data-end=\"1879\">Impacto en el mercado de la carne<\/h2>\n<p data-start=\"1880\" data-end=\"2124\">Este proceso de retenci\u00f3n y desv\u00edo hacia la recr\u00eda <strong data-start=\"1931\" data-end=\"1961\">ajusta la oferta de ganado<\/strong>, en un contexto donde la demanda interna y externa contin\u00faa firme. La consecuencia directa es una <strong data-start=\"2060\" data-end=\"2097\">presi\u00f3n alcista sobre los precios<\/strong> en el mercado de la carne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La falta de ganado en Argentina es cada vez m\u00e1s evidente, seg\u00fan la C\u00e1mara Argentina de Matarifes y Abastecedores (CAMYA), que viene alertando sobre la suba del precio de la carne y la menor disponibilidad de hacienda lista para faena. Retenci\u00f3n de animales y menor oferta de hacienda De acuerdo con Sergio Pedace, vicepresidente de [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":67442,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[267],"tags":[689,154],"commodity":[40],"class_list":["post-67620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio-es","tag-camya","tag-carnes","commodity-carne-vacuna"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Falta de ganado en Argentina; C\u00e1mara advierte<\/title>\n<meta name=\"description\" content=\"CAMYA advierte falta de ganado en Argentina por retenci\u00f3n de animales y desv\u00edo hacia la recr\u00eda, lo que presiona los precios de la carne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Falta de ganado en Argentina; C\u00e1mara advierte\" \/>\n<meta property=\"og:description\" content=\"CAMYA advierte falta de ganado en Argentina por retenci\u00f3n de animales y desv\u00edo hacia la recr\u00eda, lo que presiona los precios de la carne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-26T15:40:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julieta Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julieta Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/\"},\"author\":{\"name\":\"Julieta Marino\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\"},\"headline\":\"C\u00e1mara advierte que falta ganado en Argentina y que productores est\u00e1n reteniendo animales\",\"datePublished\":\"2025-11-26T15:40:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/\"},\"wordCount\":219,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg\",\"keywords\":[\"camya\",\"carnes\"],\"articleSection\":[\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/\",\"url\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/\",\"name\":\"Falta de ganado en Argentina; C\u00e1mara advierte\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg\",\"datePublished\":\"2025-11-26T15:40:10+00:00\",\"description\":\"CAMYA advierte falta de ganado en Argentina por retenci\u00f3n de animales y desv\u00edo hacia la recr\u00eda, lo que presiona los precios de la carne.\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg\",\"width\":1600,\"height\":1066,\"caption\":\"VACAS SECRETARIA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e1mara advierte que falta ganado en Argentina y que productores est\u00e1n reteniendo animales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\",\"name\":\"Julieta Marino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"caption\":\"Julieta Marino\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_julieta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Falta de ganado en Argentina; C\u00e1mara advierte","description":"CAMYA advierte falta de ganado en Argentina por retenci\u00f3n de animales y desv\u00edo hacia la recr\u00eda, lo que presiona los precios de la carne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/","og_locale":"es_ES","og_type":"article","og_title":"Falta de ganado en Argentina; C\u00e1mara advierte","og_description":"CAMYA advierte falta de ganado en Argentina por retenci\u00f3n de animales y desv\u00edo hacia la recr\u00eda, lo que presiona los precios de la carne.","og_url":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-11-26T15:40:10+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg","type":"image\/jpeg"}],"author":"Julieta Marino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julieta Marino","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/"},"author":{"name":"Julieta Marino","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774"},"headline":"C\u00e1mara advierte que falta ganado en Argentina y que productores est\u00e1n reteniendo animales","datePublished":"2025-11-26T15:40:10+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/"},"wordCount":219,"commentCount":3,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg","keywords":["camya","carnes"],"articleSection":["Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/","url":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/","name":"Falta de ganado en Argentina; C\u00e1mara advierte","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg","datePublished":"2025-11-26T15:40:10+00:00","description":"CAMYA advierte falta de ganado en Argentina por retenci\u00f3n de animales y desv\u00edo hacia la recr\u00eda, lo que presiona los precios de la carne.","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/VACAS-SECRETARIA.jpeg","width":1600,"height":1066,"caption":"VACAS SECRETARIA"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/camara-advierte-que-falta-ganado-y-que-productores-estan-reteniendo-animales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00e1mara advierte que falta ganado en Argentina y que productores est\u00e1n reteniendo animales"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774","name":"Julieta Marino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","caption":"Julieta Marino"},"url":"https:\/\/safras.com.br\/es\/author\/sf_julieta\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=67620"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67620\/revisions"}],"predecessor-version":[{"id":67621,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67620\/revisions\/67621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/67442"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=67620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=67620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=67620"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=67620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}