{"id":67607,"date":"2025-11-25T17:04:13","date_gmt":"2025-11-25T20:04:13","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=67607"},"modified":"2025-11-25T17:04:13","modified_gmt":"2025-11-25T20:04:13","slug":"gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/","title":{"rendered":"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026"},"content":{"rendered":"<p>El gobierno de <strong>C\u00f3rdoba<\/strong> convoc\u00f3 a empresas, c\u00e1maras y organismos provinciales para elaborar un plan de trabajo para 2026 en el sector bioenerg\u00e9tico e impulsar los <a href=\"https:\/\/safras.com.br\/es\/proyecto-de-ley-debe-garantizar-libertad-y-competitividad-para-mejorar-la-produccion-dice-zubizarreta\/\">biocombustibles<\/a>.<\/p>\n<p>Durante la jornada, hubo presentaciones de avances sobre expendios y producci\u00f3n de biodiesel, se evalu\u00f3 la situaci\u00f3n actual de PyMES productoras de biodiesel y se expusieron reg\u00edmenes fiscales.<\/p>\n<p>Con el objetivo de impulsar la transici\u00f3n energ\u00e9tica, de cara a los pr\u00f3ximos a\u00f1os, el director provincial de Biocombustibles y Bioenerg\u00edas, Mariano Santill\u00e1n, sostuvo que se deben profundizar los alcances de la ley 10.721 y generar una cadena de valor agregado al sector agropecuario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de C\u00f3rdoba convoc\u00f3 a empresas, c\u00e1maras y organismos provinciales para elaborar un plan de trabajo para 2026 en el sector bioenerg\u00e9tico e impulsar los biocombustibles. Durante la jornada, hubo presentaciones de avances sobre expendios y producci\u00f3n de biodiesel, se evalu\u00f3 la situaci\u00f3n actual de PyMES productoras de biodiesel y se expusieron reg\u00edmenes fiscales. [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":67127,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[267],"tags":[349],"commodity":[46,47,49],"class_list":["post-67607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio-es","tag-biocombustibles","commodity-maiz","commodity-soja","commodity-trigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026 - SAFRAS &amp; Mercado<\/title>\n<meta name=\"description\" content=\"El gobierno de C\u00f3rdoba cre\u00f3 una mesa de trabajo para impulsar el sector bioenerg\u00e9tico y los biocombustibles en la provincia durante 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026 - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"El gobierno de C\u00f3rdoba cre\u00f3 una mesa de trabajo para impulsar el sector bioenerg\u00e9tico y los biocombustibles en la provincia durante 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-25T20:04:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"568\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"geronimo kener\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"geronimo kener\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/\"},\"author\":{\"name\":\"geronimo kener\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3c7009f94cf442d9df6f2cd1eedd0bfd\"},\"headline\":\"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026\",\"datePublished\":\"2025-11-25T20:04:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/\"},\"wordCount\":121,\"commentCount\":11,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg\",\"keywords\":[\"biocombustibles\"],\"articleSection\":[\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/\",\"url\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/\",\"name\":\"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026 - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg\",\"datePublished\":\"2025-11-25T20:04:13+00:00\",\"description\":\"El gobierno de C\u00f3rdoba cre\u00f3 una mesa de trabajo para impulsar el sector bioenerg\u00e9tico y los biocombustibles en la provincia durante 2026.\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg\",\"width\":568,\"height\":426,\"caption\":\"Biocombustibles\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3c7009f94cf442d9df6f2cd1eedd0bfd\",\"name\":\"geronimo kener\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/97803e93b95c46f5640aea59976da81aba4ba2ddb9a9f119122d0a068646612f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/97803e93b95c46f5640aea59976da81aba4ba2ddb9a9f119122d0a068646612f?s=96&d=mm&r=g\",\"caption\":\"geronimo kener\"},\"sameAs\":[\"http:\/\/safras.com.br\/es\"],\"url\":\"https:\/\/safras.com.br\/es\/author\/geronimo-kener\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026 - SAFRAS &amp; Mercado","description":"El gobierno de C\u00f3rdoba cre\u00f3 una mesa de trabajo para impulsar el sector bioenerg\u00e9tico y los biocombustibles en la provincia durante 2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026 - SAFRAS &amp; Mercado","og_description":"El gobierno de C\u00f3rdoba cre\u00f3 una mesa de trabajo para impulsar el sector bioenerg\u00e9tico y los biocombustibles en la provincia durante 2026.","og_url":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-11-25T20:04:13+00:00","og_image":[{"width":568,"height":426,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg","type":"image\/jpeg"}],"author":"geronimo kener","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"geronimo kener","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/"},"author":{"name":"geronimo kener","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3c7009f94cf442d9df6f2cd1eedd0bfd"},"headline":"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026","datePublished":"2025-11-25T20:04:13+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/"},"wordCount":121,"commentCount":11,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg","keywords":["biocombustibles"],"articleSection":["Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/","url":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/","name":"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026 - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg","datePublished":"2025-11-25T20:04:13+00:00","description":"El gobierno de C\u00f3rdoba cre\u00f3 una mesa de trabajo para impulsar el sector bioenerg\u00e9tico y los biocombustibles en la provincia durante 2026.","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/10\/Biocombustibles-Climaterra.org_.jpg","width":568,"height":426,"caption":"Biocombustibles"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/gobierno-de-cordoba-crea-mesa-de-trabajo-para-impulsar-biocombustibles-en-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Gobierno de C\u00f3rdoba crea mesa de trabajo para impulsar biocombustibles en 2026"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3c7009f94cf442d9df6f2cd1eedd0bfd","name":"geronimo kener","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/97803e93b95c46f5640aea59976da81aba4ba2ddb9a9f119122d0a068646612f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97803e93b95c46f5640aea59976da81aba4ba2ddb9a9f119122d0a068646612f?s=96&d=mm&r=g","caption":"geronimo kener"},"sameAs":["http:\/\/safras.com.br\/es"],"url":"https:\/\/safras.com.br\/es\/author\/geronimo-kener\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=67607"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67607\/revisions"}],"predecessor-version":[{"id":67608,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67607\/revisions\/67608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/67127"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=67607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=67607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=67607"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=67607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}