{"id":67380,"date":"2025-11-03T12:56:32","date_gmt":"2025-11-03T15:56:32","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=67380"},"modified":"2025-11-04T16:10:42","modified_gmt":"2025-11-04T19:10:42","slug":"precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/","title":{"rendered":"Fertilizantes registran actividad ralentizada y precios calmos en Argentina"},"content":{"rendered":"<p>La actividad comercial de fertilizantes en Argentina contin\u00faa ralentizada, reflejando una combinaci\u00f3n de factores pol\u00edticos, clim\u00e1ticos y log\u00edsticos que siguen condicionando las decisiones del productor.<\/p>\n<p>De acuerdo con Ingenier\u00eda en Fertilizantes, en varias regiones, las lluvias recientes dejaron zonas anegadas y caminos complicados, lo que fren\u00f3 moment\u00e1neamente tanto las labores como las compras de insumos.<\/p>\n<p>\u00abLos importadores y distribuidores mantienen sus estrategias conservadoras, sin grandes modificaciones en los valores y con operaciones limitadas, principalmente enfocadas en compromisos ya asumidos. La demanda sigue sin reaccionar, con los productores priorizando la observaci\u00f3n de la evoluci\u00f3n clim\u00e1tica antes de tomar nuevas decisiones de compra para la gruesa\u00bb, se\u00f1ala el reporte.<\/p>\n<p>Para nitrogenados, los precios se ubicaron en US$ 440450 CFR, impulsados por la firmeza global y la menor oferta local por el mantenimiento de Profertil. La demanda se mantiene activa para ma\u00edz y mezclas NPS, aunque los vol\u00famenes de compra son moderados.<\/p>\n<p>Respecto a los fosfatados, en Argentina, el DAP\/MAP se sostuvo en torno a US$745 CFR, con nula actividad comercial y operadores a la espera de referencias externas para la pr\u00f3xima campa\u00f1a<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actividad comercial de fertilizantes en Argentina contin\u00faa ralentizada, reflejando una combinaci\u00f3n de factores pol\u00edticos, clim\u00e1ticos y log\u00edsticos que siguen condicionando las decisiones del productor. De acuerdo con Ingenier\u00eda en Fertilizantes, en varias regiones, las lluvias recientes dejaron zonas anegadas y caminos complicados, lo que fren\u00f3 moment\u00e1neamente tanto las labores como las compras de insumos. [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":67381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[267],"tags":[292],"commodity":[44],"class_list":["post-67380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio-es","tag-fertilizantes","commodity-fertilizantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fertilizantes registran actividad ralentizada y precios calmos en Argentina - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fertilizantes registran actividad ralentizada y precios calmos en Argentina - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"La actividad comercial de fertilizantes en Argentina contin\u00faa ralentizada, reflejando una combinaci\u00f3n de factores pol\u00edticos, clim\u00e1ticos y log\u00edsticos que siguen condicionando las decisiones del productor. De acuerdo con Ingenier\u00eda en Fertilizantes, en varias regiones, las lluvias recientes dejaron zonas anegadas y caminos complicados, lo que fren\u00f3 moment\u00e1neamente tanto las labores como las compras de insumos. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-03T15:56:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T19:10:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"383\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julieta Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julieta Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/\"},\"author\":{\"name\":\"Julieta Marino\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\"},\"headline\":\"Fertilizantes registran actividad ralentizada y precios calmos en Argentina\",\"datePublished\":\"2025-11-03T15:56:32+00:00\",\"dateModified\":\"2025-11-04T19:10:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/\"},\"wordCount\":204,\"commentCount\":338,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg\",\"keywords\":[\"Fertilizantes\"],\"articleSection\":[\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/\",\"url\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/\",\"name\":\"Fertilizantes registran actividad ralentizada y precios calmos en Argentina - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg\",\"datePublished\":\"2025-11-03T15:56:32+00:00\",\"dateModified\":\"2025-11-04T19:10:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg\",\"width\":612,\"height\":383,\"caption\":\"Fertilizantes\/ Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fertilizantes registran actividad ralentizada y precios calmos en Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\",\"name\":\"Julieta Marino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"caption\":\"Julieta Marino\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_julieta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fertilizantes registran actividad ralentizada y precios calmos en Argentina - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/","og_locale":"es_ES","og_type":"article","og_title":"Fertilizantes registran actividad ralentizada y precios calmos en Argentina - SAFRAS &amp; Mercado","og_description":"La actividad comercial de fertilizantes en Argentina contin\u00faa ralentizada, reflejando una combinaci\u00f3n de factores pol\u00edticos, clim\u00e1ticos y log\u00edsticos que siguen condicionando las decisiones del productor. De acuerdo con Ingenier\u00eda en Fertilizantes, en varias regiones, las lluvias recientes dejaron zonas anegadas y caminos complicados, lo que fren\u00f3 moment\u00e1neamente tanto las labores como las compras de insumos. [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-11-03T15:56:32+00:00","article_modified_time":"2025-11-04T19:10:42+00:00","og_image":[{"width":612,"height":383,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg","type":"image\/jpeg"}],"author":"Julieta Marino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julieta Marino","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/"},"author":{"name":"Julieta Marino","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774"},"headline":"Fertilizantes registran actividad ralentizada y precios calmos en Argentina","datePublished":"2025-11-03T15:56:32+00:00","dateModified":"2025-11-04T19:10:42+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/"},"wordCount":204,"commentCount":338,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg","keywords":["Fertilizantes"],"articleSection":["Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/","url":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/","name":"Fertilizantes registran actividad ralentizada y precios calmos en Argentina - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg","datePublished":"2025-11-03T15:56:32+00:00","dateModified":"2025-11-04T19:10:42+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/11\/fertilizantes.jpg","width":612,"height":383,"caption":"Fertilizantes\/ Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/precios-calmos-y-actividad-ralentizada-marcan-la-semana-en-argentina-if\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Fertilizantes registran actividad ralentizada y precios calmos en Argentina"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774","name":"Julieta Marino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","caption":"Julieta Marino"},"url":"https:\/\/safras.com.br\/es\/author\/sf_julieta\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=67380"}],"version-history":[{"count":2,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67380\/revisions"}],"predecessor-version":[{"id":67405,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/67380\/revisions\/67405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/67381"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=67380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=67380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=67380"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=67380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}