{"id":66803,"date":"2025-09-11T14:26:05","date_gmt":"2025-09-11T17:26:05","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=66803"},"modified":"2025-09-11T14:26:11","modified_gmt":"2025-09-11T17:26:11","slug":"indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/","title":{"rendered":"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual"},"content":{"rendered":"<p>El Indice de Precios al Consumidor (CPI, por sus siglas en ingl\u00e9s) de Estados Unidos subi\u00f3 un 0,4% en agosto frente al mes anterior, ya descontados los factores estacionales, seg\u00fan datos del Departamento de Trabajo del pa\u00eds. La cifra super\u00f3 la previsi\u00f3n del mercado, que apuntaba a un alza del 0,3%. En julio, el \u00edndice hab\u00eda aumentado un<br \/>\n0,2% respecto a junio. En los 12 meses hasta agosto, el CPI subi\u00f3 un 2,9%, en l\u00ednea con lo esperado por el mercado.<\/p>\n<p>En la comparaci\u00f3n mensual, el \u00edndice subyacente de precios al consumidor, que excluye las variaciones de alimentos y energ\u00eda, avanz\u00f3 un 0,3% en agosto, el mismo incremento registrado en julio. En los 12 meses terminados en agosto, el n\u00facleo del CPI subi\u00f3 un 3,1%, tambi\u00e9n igual al registrado en julio.<\/p>\n<p>El \u00edndice de precios de la energ\u00eda aument\u00f3 un 0,7% en agosto frente al mes anterior, tras haber ca\u00eddo un 1,1% en julio. El \u00edndice de precios de los alimentos subi\u00f3 un 0,5% en agosto, despu\u00e9s de haberse mantenido estable en julio. En los 12 meses hasta agosto, el sub\u00edndice de energ\u00eda subi\u00f3 un 0,2%, mientras que el de alimentos creci\u00f3 un 3,2%.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Indice de Precios al Consumidor (CPI, por sus siglas en ingl\u00e9s) de Estados Unidos subi\u00f3 un 0,4% en agosto frente al mes anterior, ya descontados los factores estacionales, seg\u00fan datos del Departamento de Trabajo del pa\u00eds. La cifra super\u00f3 la previsi\u00f3n del mercado, que apuntaba a un alza del 0,3%. En julio, el \u00edndice [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":66427,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[444],"tags":[372],"commodity":[],"class_list":["post-66803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras","tag-eeuu"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"El Indice de Precios al Consumidor (CPI, por sus siglas en ingl\u00e9s) de Estados Unidos subi\u00f3 un 0,4% en agosto frente al mes anterior, ya descontados los factores estacionales, seg\u00fan datos del Departamento de Trabajo del pa\u00eds. La cifra super\u00f3 la previsi\u00f3n del mercado, que apuntaba a un alza del 0,3%. En julio, el \u00edndice [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-11T17:26:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-11T17:26:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julieta Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julieta Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/\"},\"author\":{\"name\":\"Julieta Marino\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\"},\"headline\":\"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual\",\"datePublished\":\"2025-09-11T17:26:05+00:00\",\"dateModified\":\"2025-09-11T17:26:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/\"},\"wordCount\":210,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg\",\"keywords\":[\"eeuu\"],\"articleSection\":[\"Noticias Financieras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/\",\"url\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/\",\"name\":\"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg\",\"datePublished\":\"2025-09-11T17:26:05+00:00\",\"dateModified\":\"2025-09-11T17:26:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Nueva York Pixabay EEUU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\",\"name\":\"Julieta Marino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"caption\":\"Julieta Marino\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_julieta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/","og_locale":"es_ES","og_type":"article","og_title":"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual - SAFRAS &amp; Mercado","og_description":"El Indice de Precios al Consumidor (CPI, por sus siglas en ingl\u00e9s) de Estados Unidos subi\u00f3 un 0,4% en agosto frente al mes anterior, ya descontados los factores estacionales, seg\u00fan datos del Departamento de Trabajo del pa\u00eds. La cifra super\u00f3 la previsi\u00f3n del mercado, que apuntaba a un alza del 0,3%. En julio, el \u00edndice [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-09-11T17:26:05+00:00","article_modified_time":"2025-09-11T17:26:11+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg","type":"image\/jpeg"}],"author":"Julieta Marino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julieta Marino","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/"},"author":{"name":"Julieta Marino","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774"},"headline":"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual","datePublished":"2025-09-11T17:26:05+00:00","dateModified":"2025-09-11T17:26:11+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/"},"wordCount":210,"commentCount":3,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg","keywords":["eeuu"],"articleSection":["Noticias Financieras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/","url":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/","name":"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg","datePublished":"2025-09-11T17:26:05+00:00","dateModified":"2025-09-11T17:26:11+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/Nueva-York-Pixabay-EEUU.jpg","width":1280,"height":853,"caption":"Nueva York Pixabay EEUU"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/indice-de-precios-al-consumidor-de-ee-uu-sube-04-en-agosto-en-base-mensual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Indice de precios al consumidor de EE.UU sube 0,4% en agosto en base mensual"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774","name":"Julieta Marino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","caption":"Julieta Marino"},"url":"https:\/\/safras.com.br\/es\/author\/sf_julieta\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=66803"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66803\/revisions"}],"predecessor-version":[{"id":66804,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66803\/revisions\/66804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/66427"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=66803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=66803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=66803"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=66803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}