{"id":66445,"date":"2025-08-13T12:48:36","date_gmt":"2025-08-13T15:48:36","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=66445"},"modified":"2025-08-13T12:51:07","modified_gmt":"2025-08-13T15:51:07","slug":"ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/","title":{"rendered":"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24"},"content":{"rendered":"<p>La petrolera Ecopetrol report\u00f3 una utilidad neta consolidada atribuible a los accionistas para el segundo trimestre de 2025 de $1,8 billones de pesos colombianos una ca\u00edda de 46,4% ante mismo per\u00edodo de 2024.<\/p>\n<p>&nbsp;<\/p>\n<p>En el per\u00edodo de an\u00e1lisis el Ebitda fue de 11,1 billones de pesos, con un margen Ebitda de 37,5%.<\/p>\n<p>&nbsp;<\/p>\n<p>De esta manera, en el primer semestre del a\u00f1o se registraron ingresos por 61,0 billones, un EBITDA de 24,4 billones con un margen de 40% y una utilidad neta de 4.9 billones<\/p>\n<p>&nbsp;<\/p>\n<p>Los ingresos por ventas en el 2T25 sumaron $29,7 billones presentando una reducci\u00f3n de 9,1% correspondientes a -3.0 billones respecto al 2T24.<\/p>\n<p>&nbsp;<\/p>\n<p>La producci\u00f3n bruta del Grupo Ecopetrol fue de 755,5 mil barriles de petr\u00f3leo equivalente por d\u00eda (kbped), de los cuales Ecopetrol S.A. aport\u00f3 595,4 kbped. Ante el mismo per\u00edodo de 2024, la producci\u00f3n total del Grupo subi\u00f3 0,5%.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La petrolera Ecopetrol report\u00f3 una utilidad neta consolidada atribuible a los accionistas para el segundo trimestre de 2025 de $1,8 billones de pesos colombianos una ca\u00edda de 46,4% ante mismo per\u00edodo de 2024. &nbsp; En el per\u00edodo de an\u00e1lisis el Ebitda fue de 11,1 billones de pesos, con un margen Ebitda de 37,5%. &nbsp; De [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":66450,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[399,444],"tags":[],"commodity":[],"class_list":["post-66445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas","category-noticias-financieras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24 - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24 - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"La petrolera Ecopetrol report\u00f3 una utilidad neta consolidada atribuible a los accionistas para el segundo trimestre de 2025 de $1,8 billones de pesos colombianos una ca\u00edda de 46,4% ante mismo per\u00edodo de 2024. &nbsp; En el per\u00edodo de an\u00e1lisis el Ebitda fue de 11,1 billones de pesos, con un margen Ebitda de 37,5%. &nbsp; De [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-13T15:48:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T15:51:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julieta Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julieta Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/\"},\"author\":{\"name\":\"Julieta Marino\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\"},\"headline\":\"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24\",\"datePublished\":\"2025-08-13T15:48:36+00:00\",\"dateModified\":\"2025-08-13T15:51:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/\"},\"wordCount\":158,\"commentCount\":7,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png\",\"articleSection\":[\"Empresas\",\"Noticias Financieras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/\",\"url\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/\",\"name\":\"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24 - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png\",\"datePublished\":\"2025-08-13T15:48:36+00:00\",\"dateModified\":\"2025-08-13T15:51:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png\",\"width\":720,\"height\":720,\"caption\":\"ecopetrol3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\",\"name\":\"Julieta Marino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"caption\":\"Julieta Marino\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_julieta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24 - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/","og_locale":"es_ES","og_type":"article","og_title":"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24 - SAFRAS &amp; Mercado","og_description":"La petrolera Ecopetrol report\u00f3 una utilidad neta consolidada atribuible a los accionistas para el segundo trimestre de 2025 de $1,8 billones de pesos colombianos una ca\u00edda de 46,4% ante mismo per\u00edodo de 2024. &nbsp; En el per\u00edodo de an\u00e1lisis el Ebitda fue de 11,1 billones de pesos, con un margen Ebitda de 37,5%. &nbsp; De [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-08-13T15:48:36+00:00","article_modified_time":"2025-08-13T15:51:07+00:00","og_image":[{"width":720,"height":720,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png","type":"image\/png"}],"author":"Julieta Marino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julieta Marino","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/"},"author":{"name":"Julieta Marino","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774"},"headline":"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24","datePublished":"2025-08-13T15:48:36+00:00","dateModified":"2025-08-13T15:51:07+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/"},"wordCount":158,"commentCount":7,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png","articleSection":["Empresas","Noticias Financieras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/","url":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/","name":"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24 - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png","datePublished":"2025-08-13T15:48:36+00:00","dateModified":"2025-08-13T15:51:07+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/ecopetrol3.png","width":720,"height":720,"caption":"ecopetrol3"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/ganancia-neta-de-ecopetrol-suma-18-billones-en-2t25-caida-de-464-ante-2t24\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Ganancia neta de Ecopetrol suma $1,8 billones en 2T25, ca\u00edda de 46,4% ante 2T24"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774","name":"Julieta Marino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","caption":"Julieta Marino"},"url":"https:\/\/safras.com.br\/es\/author\/sf_julieta\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=66445"}],"version-history":[{"count":3,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66445\/revisions"}],"predecessor-version":[{"id":66451,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66445\/revisions\/66451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/66450"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=66445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=66445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=66445"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=66445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}