{"id":66444,"date":"2025-08-13T12:59:47","date_gmt":"2025-08-13T15:59:47","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=66444"},"modified":"2025-08-13T13:00:13","modified_gmt":"2025-08-13T16:00:13","slug":"wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/","title":{"rendered":"WASDE de agosto sorprende con ajustes en stocks y rendimientos"},"content":{"rendered":"<p>El WASDE de agosto sorprendi\u00f3 al mercado con ajustes en los stocks de Estados Unidos para 2024\/25 y cambios en los rendimientos esperados para soja y ma\u00edz para la campa\u00f1a 2025\/26. Los analistas de Safras &amp; Mercado Agust\u00edn Geier, Patricio Tom\u00e1s Murphy y Andr\u00e9s Cannizzo conversan con la editora de la agencia Safras News Latam, Julieta Marino y explican los impactos.<\/p>\n<p>Mir\u00e1 el video en los enlaces a continuaci\u00f3n, en SAFRAS TV y en YouTube:<\/p>\n<p><iframe loading=\"lazy\" title=\"WASDE de agosto sorprende con ajustes en stocks y rendimientos\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/p4Wh55DHh0I?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/safras.com.br\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Siga en Safras TV, videos del equipo de periodistas y analistas de Safras &amp; Mercado, con<br \/>\ninformaci\u00f3n sobre el movimiento de los principales mercados de Argentina y del mundo para productos<br \/>\nagr\u00edcolas.<\/p>\n<p>Contenido de Safras TV:<\/p>\n<p>&#8211; Mercados agr\u00edcolas: seguimiento de los mercados de soja, ma\u00edz, trigo, caf\u00e9, carne y<br \/>\nfertilizantes<br \/>\n&#8211; Agenda semanal: los principales acontecimientos del sector y su impacto en el mercado.<br \/>\n&#8211; Entrevistas: conversaciones mensuales con analistas de Safras &amp; Mercado y otros representantes del<br \/>\nsector de los temas m\u00e1s relevantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El WASDE de agosto sorprendi\u00f3 al mercado con ajustes en los stocks de Estados Unidos para 2024\/25 y cambios en los rendimientos esperados para soja y ma\u00edz para la campa\u00f1a 2025\/26. Los analistas de Safras &amp; Mercado Agust\u00edn Geier, Patricio Tom\u00e1s Murphy y Andr\u00e9s Cannizzo conversan con la editora de la agencia Safras News Latam, [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":66455,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[267],"tags":[606,332,330],"commodity":[46,47,49],"class_list":["post-66444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio-es","tag-agosto","tag-usda-es","tag-wasde-es","commodity-maiz","commodity-soja","commodity-trigo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>WASDE de agosto sorprende con ajustes en stocks y rendimientos - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WASDE de agosto sorprende con ajustes en stocks y rendimientos - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"El WASDE de agosto sorprendi\u00f3 al mercado con ajustes en los stocks de Estados Unidos para 2024\/25 y cambios en los rendimientos esperados para soja y ma\u00edz para la campa\u00f1a 2025\/26. Los analistas de Safras &amp; Mercado Agust\u00edn Geier, Patricio Tom\u00e1s Murphy y Andr\u00e9s Cannizzo conversan con la editora de la agencia Safras News Latam, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-13T15:59:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T16:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"923\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julieta Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julieta Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/\"},\"author\":{\"name\":\"Julieta Marino\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\"},\"headline\":\"WASDE de agosto sorprende con ajustes en stocks y rendimientos\",\"datePublished\":\"2025-08-13T15:59:47+00:00\",\"dateModified\":\"2025-08-13T16:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/\"},\"wordCount\":186,\"commentCount\":347,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg\",\"keywords\":[\"agosto\",\"USDA\",\"wasde\"],\"articleSection\":[\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/\",\"url\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/\",\"name\":\"WASDE de agosto sorprende con ajustes en stocks y rendimientos - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg\",\"datePublished\":\"2025-08-13T15:59:47+00:00\",\"dateModified\":\"2025-08-13T16:00:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg\",\"width\":923,\"height\":646,\"caption\":\"WASDE agosto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WASDE de agosto sorprende con ajustes en stocks y rendimientos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\",\"name\":\"Julieta Marino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"caption\":\"Julieta Marino\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_julieta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WASDE de agosto sorprende con ajustes en stocks y rendimientos - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/","og_locale":"es_ES","og_type":"article","og_title":"WASDE de agosto sorprende con ajustes en stocks y rendimientos - SAFRAS &amp; Mercado","og_description":"El WASDE de agosto sorprendi\u00f3 al mercado con ajustes en los stocks de Estados Unidos para 2024\/25 y cambios en los rendimientos esperados para soja y ma\u00edz para la campa\u00f1a 2025\/26. Los analistas de Safras &amp; Mercado Agust\u00edn Geier, Patricio Tom\u00e1s Murphy y Andr\u00e9s Cannizzo conversan con la editora de la agencia Safras News Latam, [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-08-13T15:59:47+00:00","article_modified_time":"2025-08-13T16:00:13+00:00","og_image":[{"width":923,"height":646,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg","type":"image\/jpeg"}],"author":"Julieta Marino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julieta Marino","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/"},"author":{"name":"Julieta Marino","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774"},"headline":"WASDE de agosto sorprende con ajustes en stocks y rendimientos","datePublished":"2025-08-13T15:59:47+00:00","dateModified":"2025-08-13T16:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/"},"wordCount":186,"commentCount":347,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg","keywords":["agosto","USDA","wasde"],"articleSection":["Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/","url":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/","name":"WASDE de agosto sorprende con ajustes en stocks y rendimientos - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg","datePublished":"2025-08-13T15:59:47+00:00","dateModified":"2025-08-13T16:00:13+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/WASDE-agosto.jpg","width":923,"height":646,"caption":"WASDE agosto"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/wasde-de-agosto-sorprende-con-ajustes-en-stocks-y-rendimientos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"WASDE de agosto sorprende con ajustes en stocks y rendimientos"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774","name":"Julieta Marino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","caption":"Julieta Marino"},"url":"https:\/\/safras.com.br\/es\/author\/sf_julieta\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=66444"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66444\/revisions"}],"predecessor-version":[{"id":66456,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66444\/revisions\/66456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/66455"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=66444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=66444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=66444"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=66444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}