{"id":66315,"date":"2025-08-04T14:39:35","date_gmt":"2025-08-04T17:39:35","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=66315"},"modified":"2025-08-04T14:39:35","modified_gmt":"2025-08-04T17:39:35","slug":"fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/","title":{"rendered":"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o"},"content":{"rendered":"<p>El Fondo Monetario Internacional (FMI) espera que las reservas de la Argentina en culminen negativas en US$ 2.600 millones en lugar del objetivo previo de US$ 2.400 millones positivos. Para fines de 2026, la meta pasa de US$ 10.400 millones a US$ 8.400 millones positivos. A su vez, se mantiene la meta de US$ 22.900 millones positivos para 2027, trasladando el mayor esfuerzo al final del mandato de Javier Milei.<\/p>\n<p>&nbsp;<\/p>\n<p>El FMI justific\u00f3 la flexibilizaci\u00f3n por la implementaci\u00f3n de \u201cmedidas correctivas\u201d y una nueva estrategia de compra de divisas que incluir\u00e1 la privatizaci\u00f3n de empresas p\u00fablicas, emisi\u00f3n de bonos y apoyo de acreedores oficiales. Tambi\u00e9n modific\u00f3 el calendario de revisiones: la pr\u00f3xima ser\u00e1 en enero de 2026.<\/p>\n<p>&nbsp;<\/p>\n<p>Aunque Argentina incumpli\u00f3 la meta de reservas en junio, alcanz\u00f3 otros objetivos fiscales y monetarios clave. El organismo destac\u00f3 un comienzo s\u00f3lido del programa, aunque advirti\u00f3 sobre riesgos como la volatilidad electoral, la dependencia de capitales especulativos y el riesgo de desequilibrios macroecon\u00f3micos.<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n, el FMI respald\u00f3 el rol del Tesoro en la acumulaci\u00f3n de reservas y pidi\u00f3 un Banco Central m\u00e1s activo, con referencia a modelos de Chile, M\u00e9xico y Colombia. Adem\u00e1s, recomend\u00f3 endurecer la pol\u00edtica fiscal, permitir ajustes del tipo de cambio y liberar gradualmente los controles cambiarios para sostener la estabilidad.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Fondo Monetario Internacional (FMI) espera que las reservas de la Argentina en culminen negativas en US$ 2.600 millones en lugar del objetivo previo de US$ 2.400 millones positivos. Para fines de 2026, la meta pasa de US$ 10.400 millones a US$ 8.400 millones positivos. A su vez, se mantiene la meta de US$ 22.900 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":66317,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[444],"tags":[],"commodity":[],"class_list":["post-66315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-financieras"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"El Fondo Monetario Internacional (FMI) espera que las reservas de la Argentina en culminen negativas en US$ 2.600 millones en lugar del objetivo previo de US$ 2.400 millones positivos. Para fines de 2026, la meta pasa de US$ 10.400 millones a US$ 8.400 millones positivos. A su vez, se mantiene la meta de US$ 22.900 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T17:39:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Horacio Vera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Horacio Vera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/\"},\"author\":{\"name\":\"Horacio Vera\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\"},\"headline\":\"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o\",\"datePublished\":\"2025-08-04T17:39:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/\"},\"wordCount\":236,\"commentCount\":399,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg\",\"articleSection\":[\"Noticias Financieras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/\",\"url\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/\",\"name\":\"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg\",\"datePublished\":\"2025-08-04T17:39:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"xr:d:DAFRE6WWe5A:2,j:40065298366,t:22110511\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\",\"name\":\"Horacio Vera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"caption\":\"Horacio Vera\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_horacio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/","og_locale":"es_ES","og_type":"article","og_title":"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o - SAFRAS &amp; Mercado","og_description":"El Fondo Monetario Internacional (FMI) espera que las reservas de la Argentina en culminen negativas en US$ 2.600 millones en lugar del objetivo previo de US$ 2.400 millones positivos. Para fines de 2026, la meta pasa de US$ 10.400 millones a US$ 8.400 millones positivos. A su vez, se mantiene la meta de US$ 22.900 [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-08-04T17:39:35+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg","type":"image\/jpeg"}],"author":"Horacio Vera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Horacio Vera","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/"},"author":{"name":"Horacio Vera","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747"},"headline":"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o","datePublished":"2025-08-04T17:39:35+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/"},"wordCount":236,"commentCount":399,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg","articleSection":["Noticias Financieras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/","url":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/","name":"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg","datePublished":"2025-08-04T17:39:35+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/08\/FMI3.jpg","width":1920,"height":1080,"caption":"xr:d:DAFRE6WWe5A:2,j:40065298366,t:22110511"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/fmi-confirma-reduccion-de-meta-de-reservas-para-argentina-para-este-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"FMI confirma reducci\u00f3n de meta de reservas para Argentina para este a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747","name":"Horacio Vera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","caption":"Horacio Vera"},"url":"https:\/\/safras.com.br\/es\/author\/sf_horacio\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=66315"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66315\/revisions"}],"predecessor-version":[{"id":66318,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66315\/revisions\/66318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/66317"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=66315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=66315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=66315"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=66315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}