{"id":66204,"date":"2025-07-22T11:45:52","date_gmt":"2025-07-22T14:45:52","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=66204"},"modified":"2025-07-22T11:45:52","modified_gmt":"2025-07-22T14:45:52","slug":"mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/","title":{"rendered":"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios"},"content":{"rendered":"<p>El mercado est\u00e1 priceando una baja de retenciones, con la misma al\u00edcuota que se tuvo durante la reducci\u00f3n temporal de enero a junio, esto es en 26% desde el actual 33% para la nueva campa\u00f1a 2025\/26 lo que sustentar\u00eda que la soja mayo sea \u201ccara\u201d respecto de la noviembre.<\/p>\n<p>&nbsp;<\/p>\n<p>El analista de Safras &amp; Mercado, Agust\u00edn Geier, explica que el valor de la soja mayo\/26 ronda los 282 usd\/ton en el mercado de futuros lo que resulta \u201cllamativo\u201d dado que el pase con la noviembre\/25 pr\u00e1cticamente no muestra diferenciales mientras que el promedio hist\u00f3rico indica que deber\u00eda estar en 25 usd\/ton a favor de la posici\u00f3n de noviembre respecto de la \u201cnew crop\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Partiendo de los FOB de referencia de la base de los 282 usd\/Ton con un FOB te\u00f3rico considerando DEX de 33% (que ser\u00eda la al\u00edcuota actual), da que el FOB deber\u00eda valer 431 usd\/Ton.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00abSin embargo, la referencia para mayo\/26 ronda los 391 usd\/ton, valor al cual llegar\u00edamos con una al\u00edcuota de 26% igual que el que tuvimos durante la baja temporal. Dicho de otra forma, si tomamos un FOB de 391 usd\/ton, nos da un FAS (Free Alongside Ship) de 282 usd\/ton que es el precio de la soja mayo 26\u00bb, explica Geier.<\/p>\n<p>&nbsp;<\/p>\n<p>ALTERNATIVAS<\/p>\n<p>&nbsp;<\/p>\n<p>Dado que en el mercado de futuros ya se est\u00e1 descontando esto, quedar\u00eda trasladarlo al f\u00edsico y podr\u00edamos ver un incremento de las operaciones sobre la nueva cosecha.<\/p>\n<p>&nbsp;<\/p>\n<p>De acuerdo con Safras &amp; Mercado, para alcanzar un resultado que sea atractivo y realmente mantenga una din\u00e1mica de compra sostenida para la nueva campa\u00f1a, la reducci\u00f3n de los DEX para los subproductos que ostentan una alicuota de 31% y tuvieron una reducci\u00f3n temporal a 24,5% deber\u00eda llegar, por lo menos, al 18% aproximadamente si se toma el precio para el poroto de 282 usd\/ton.<\/p>\n<p>&nbsp;<\/p>\n<p>Sin embargo, \u00abesto no mejorar\u00eda demasiado los valores para el mercado f\u00edsico durante la cosecha si los escenarios de precios futuros de los subproductos se cumplen\u00bb, agrega el analista.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan \u00e9l, para que esos 311 usd\/ton sean convalidados en el f\u00edsico durante la cosecha y la comercializaci\u00f3n se mantenga activa, los DEX de los subproductos deber\u00edan caer a 15% aproximadamente.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mercado est\u00e1 priceando una baja de retenciones, con la misma al\u00edcuota que se tuvo durante la reducci\u00f3n temporal de enero a junio, esto es en 26% desde el actual 33% para la nueva campa\u00f1a 2025\/26 lo que sustentar\u00eda que la soja mayo sea \u201ccara\u201d respecto de la noviembre. &nbsp; El analista de Safras &amp; [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":65688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[267],"tags":[],"commodity":[47],"class_list":["post-66204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio-es","commodity-soja"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"El mercado est\u00e1 priceando una baja de retenciones, con la misma al\u00edcuota que se tuvo durante la reducci\u00f3n temporal de enero a junio, esto es en 26% desde el actual 33% para la nueva campa\u00f1a 2025\/26 lo que sustentar\u00eda que la soja mayo sea \u201ccara\u201d respecto de la noviembre. &nbsp; El analista de Safras &amp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-22T14:45:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja-1024x768.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julieta Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julieta Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/\"},\"author\":{\"name\":\"Julieta Marino\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\"},\"headline\":\"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios\",\"datePublished\":\"2025-07-22T14:45:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/\"},\"wordCount\":404,\"commentCount\":13,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja.png\",\"articleSection\":[\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/\",\"url\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/\",\"name\":\"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja.png\",\"datePublished\":\"2025-07-22T14:45:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja.png\",\"width\":1280,\"height\":960,\"caption\":\"d\u00f3lar soja\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\",\"name\":\"Julieta Marino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"caption\":\"Julieta Marino\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_julieta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/","og_locale":"es_ES","og_type":"article","og_title":"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios - SAFRAS &amp; Mercado","og_description":"El mercado est\u00e1 priceando una baja de retenciones, con la misma al\u00edcuota que se tuvo durante la reducci\u00f3n temporal de enero a junio, esto es en 26% desde el actual 33% para la nueva campa\u00f1a 2025\/26 lo que sustentar\u00eda que la soja mayo sea \u201ccara\u201d respecto de la noviembre. &nbsp; El analista de Safras &amp; [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-07-22T14:45:52+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja-1024x768.png","type":"image\/png"}],"author":"Julieta Marino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julieta Marino","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/"},"author":{"name":"Julieta Marino","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774"},"headline":"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios","datePublished":"2025-07-22T14:45:52+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/"},"wordCount":404,"commentCount":13,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja.png","articleSection":["Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/","url":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/","name":"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja.png","datePublished":"2025-07-22T14:45:52+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/dolar-soja.png","width":1280,"height":960,"caption":"d\u00f3lar soja"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/mercado-comienza-a-pricear-baja-de-retenciones-para-campana-2025-26-safras-analiza-los-diferentes-escenarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Mercado comienza a pricear baja de retenciones para campa\u00f1a 2025\/26. Safras analiza los diferentes escenarios"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774","name":"Julieta Marino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","caption":"Julieta Marino"},"url":"https:\/\/safras.com.br\/es\/author\/sf_julieta\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=66204"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66204\/revisions"}],"predecessor-version":[{"id":66205,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/66204\/revisions\/66205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/65688"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=66204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=66204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=66204"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=66204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}