{"id":65951,"date":"2025-06-26T11:34:54","date_gmt":"2025-06-26T14:34:54","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=65951"},"modified":"2025-06-26T11:34:54","modified_gmt":"2025-06-26T14:34:54","slug":"el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/","title":{"rendered":"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina"},"content":{"rendered":"<p><strong>\u00bfPor qu\u00e9 es importante entender el balance de la industria del crushing en Argentina?<\/strong><\/p>\n<p>Comprender la din\u00e1mica de la comercializaci\u00f3n de poroto de soja en Argentina implica analizar mucho m\u00e1s que los precios o los m\u00e1rgenes de los productores. Uno de los actores clave \u2014quiz\u00e1s el m\u00e1s influyente en t\u00e9rminos de demanda local\u2014 es la industria del crushing, encargada de procesar el poroto de soja para transformarlo en harina y aceite, dos subproductos que representan una porci\u00f3n fundamental de las exportaciones agroindustriales del pa\u00eds. Por eso, analizar su balance operativo se vuelve esencial para anticipar el comportamiento del mercado interno.<\/p>\n<p><strong>El rol central del crushing en el mercado argentino<\/strong><\/p>\n<p>En Argentina, la industria del crushing no solo opera como transformadora del grano, sino como el principal motor de demanda de soja en el mercado local, ya que el pa\u00eds se destaca por el agregado de valor del grano y no exporta grandes vol\u00famenes de materia prima tal cual como es el caso de Brasil.<\/p>\n<p>Esta caracter\u00edstica vuelve fundamental monitorear cu\u00e1n abastecida est\u00e1 la industria en un momento dado. \u00bfTiene suficiente soja para cumplir con sus compromisos de exportaci\u00f3n? \u00bfTiene necesidad de salir al mercado a comprar de forma inmediata o puede esperar mejores condiciones? Estas preguntas son claves para entender el nivel de presi\u00f3n que la demanda industrial ejercer\u00e1 sobre el mercado disponible.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-65952\" title=\"Blog Safras Latam (695 x 390 px) (600 x 390 px) (1)\" src=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1-300x195.png\" alt=\"Blog Safras Latam (695 x 390 px) (600 x 390 px) (1)\" width=\"300\" height=\"195\" srcset=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1-300x195.png 300w, https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><strong>El balance del sector: \u00bfcon cu\u00e1nto grano cuenta la industria?<\/strong><\/p>\n<p>Para construir este balance, el primer paso es determinar con qu\u00e9 stock inicial cuenta la industria al inicio de la campa\u00f1a comercial. En general, se parte del supuesto de que la campa\u00f1a comienza el 1\u00b0 de abril, coincidiendo con el ingreso m\u00e1s significativo de la cosecha al circuito comercial.<\/p>\n<p>A ese stock inicial se le suman dos componentes adicionales:<\/p>\n<ol>\n<li><strong>Importaciones de poroto de soja<\/strong>, que suelen provenir mayormente de Paraguay, Bolivia o Brasil cuando la producci\u00f3n local es insuficiente.<\/li>\n<li><strong>Compras acumuladas de soja en el mercado interno<\/strong>, es decir, las operaciones realizadas por la industria desde el comienzo de la campa\u00f1a hasta la fecha de an\u00e1lisis.<\/li>\n<\/ol>\n<p>La suma de estos tres factores conforma lo que podr\u00edamos llamar la \u201cposici\u00f3n abastecida\u201d de la industria. Este es el punto de partida para analizar si el sector se encuentra bien abastecido o si, por el contrario, deber\u00e1 salir a comprar activamente grano en el corto plazo.<\/p>\n<p><strong>Estimaci\u00f3n de la demanda: DJVE y molienda<\/strong><\/p>\n<p>Con la oferta disponible definida, el siguiente paso es estimar la demanda que enfrenta la industria. Aqu\u00ed entran en juego dos indicadores fundamentales:<\/p>\n<ol>\n<li><strong>Las Declaraciones Juradas de Ventas al Exterior (DJVE)<\/strong> de harina y aceite de soja. Estas declaraciones permiten conocer cu\u00e1ntos compromisos de exportaci\u00f3n ya asumi\u00f3 el sector. Pero para poder compararlos con la oferta de grano, debemos convertir estas toneladas de subproductos a <strong>equivalente poroto<\/strong>, considerando los rindes de industrializaci\u00f3n (aproximadamente 78% de harina y 18-19% de aceite por cada tonelada de soja procesada).<\/li>\n<\/ol>\n<p>Como no se puede producir harina sin aceite (ni viceversa), se toma el <strong>mayor valor en equivalente poroto<\/strong> entre ambos productos como referencia de compromiso total. Esa ser\u00e1 la vara contra la cual compararemos el abastecimiento actual.<\/p>\n<p>Si el resultado es negativo (es decir, si las DJVE en equivalente poroto superan el abastecimiento), quiere decir que la industria a\u00fan necesita originar grano para poder cumplir con sus exportaciones. Si, en cambio, el n\u00famero es positivo, la industria podr\u00eda embarcar toda su mercader\u00eda comprometida sin tener que salir de inmediato a comprar m\u00e1s soja.<\/p>\n<ol>\n<li><strong>La molienda acumulada<\/strong>, que es el gran destino del grano: el proceso de industrializaci\u00f3n. Aqu\u00ed no solo interesa la cantidad total procesada, sino tambi\u00e9n estimar <strong>cu\u00e1nto tiempo puede seguir funcionando la industria con el abastecimiento actual<\/strong>.<\/li>\n<\/ol>\n<p>Para eso, se resta del total abastecido la molienda acumulada hasta la fecha, y el saldo resultante se divide por la <strong>molienda diaria promedio hist\u00f3rica<\/strong>. De esa manera se obtiene el n\u00famero de <strong>d\u00edas de cobertura<\/strong> que tiene la industria, es decir, cu\u00e1ntos d\u00edas m\u00e1s podr\u00eda seguir operando si no realiza nuevas compras.<\/p>\n<p><strong>Lectura del balance: \u00bfprotagonismo comprador o pausa t\u00e1ctica?<\/strong><\/p>\n<p>Este an\u00e1lisis del balance industrial permite sacar conclusiones valiosas sobre el comportamiento que puede esperarse por parte del crushing en el mercado de soja:<\/p>\n<ul>\n<li><strong>Si la industria est\u00e1 desabastecida o con poco stock remanente<\/strong>, es probable que se muestre como un comprador agresivo en el corto plazo, convalidando precios m\u00e1s altos con tal de asegurarse materia prima.<\/li>\n<li><strong>Si, en cambio, el balance muestra un abastecimiento holgado y varios d\u00edas de cobertura<\/strong>, entonces la industria puede tomarse una pausa t\u00e1ctica, sin necesidad de convalidar precios altos. En este escenario, probablemente el ritmo de compras sea m\u00e1s pausado, y la presi\u00f3n sobre el mercado disponible disminuya.<\/li>\n<\/ul>\n<p>Esta l\u00f3gica tambi\u00e9n impacta en el comportamiento de los precios locales. Un sector industrial urgido por originar grano suele ser m\u00e1s flexible en sus condiciones comerciales, elevando los valores pagados o mejorando bonificaciones. Por el contrario, cuando el abastecimiento est\u00e1 cubierto, puede ejercer una presi\u00f3n bajista sobre los precios en el mercado interno.<\/p>\n<p><strong>Conclusi\u00f3n<\/strong><\/p>\n<p>En definitiva, entender el balance de la industria del crushing no es una cuesti\u00f3n contable, sino una herramienta clave para anticipar decisiones comerciales, din\u00e1micas de precios y comportamientos de los actores m\u00e1s relevantes del mercado de soja en Argentina. En un contexto cada vez m\u00e1s vol\u00e1til y competitivo, tener claro este mapa de abastecimiento y demanda permite tomar decisiones comerciales m\u00e1s informadas, tanto para productores como para operadores y exportadores.<\/p>\n<p>Por eso, m\u00e1s all\u00e1 de las variables tradicionales del an\u00e1lisis de mercado \u2014como la producci\u00f3n, el clima o las cotizaciones internacionales\u2014, incorporar el seguimiento regular del balance del crushing a nuestro radar es una ventaja competitiva que no deber\u00edamos subestimar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 es importante entender el balance de la industria del crushing en Argentina? Comprender la din\u00e1mica de la comercializaci\u00f3n de poroto de soja en Argentina implica analizar mucho m\u00e1s que los precios o los m\u00e1rgenes de los productores. Uno de los actores clave \u2014quiz\u00e1s el m\u00e1s influyente en t\u00e9rminos de demanda local\u2014 es la [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":65952,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[306],"tags":[334,136],"commodity":[47],"class_list":["post-65951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-latam","tag-argentina-es","tag-soja","commodity-soja"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"\u00bfPor qu\u00e9 es importante entender el balance de la industria del crushing en Argentina? Comprender la din\u00e1mica de la comercializaci\u00f3n de poroto de soja en Argentina implica analizar mucho m\u00e1s que los precios o los m\u00e1rgenes de los productores. Uno de los actores clave \u2014quiz\u00e1s el m\u00e1s influyente en t\u00e9rminos de demanda local\u2014 es la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-26T14:34:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sf_marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sf_marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/\"},\"author\":{\"name\":\"sf_marketing\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/87ac33b48b170206d2f791adee2372da\"},\"headline\":\"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina\",\"datePublished\":\"2025-06-26T14:34:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/\"},\"wordCount\":1015,\"commentCount\":371,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png\",\"keywords\":[\"ARGENTINA\",\"Soja\"],\"articleSection\":[\"Blog Latam\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/\",\"url\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/\",\"name\":\"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png\",\"datePublished\":\"2025-06-26T14:34:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png\",\"width\":600,\"height\":390,\"caption\":\"Blog Safras Latam (695 x 390 px) (600 x 390 px) (1)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/87ac33b48b170206d2f791adee2372da\",\"name\":\"sf_marketing\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3e3927af6a747068b3907194947e6103dba748c72f497746d7fc79d693a247b6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3e3927af6a747068b3907194947e6103dba748c72f497746d7fc79d693a247b6?s=96&d=mm&r=g\",\"caption\":\"sf_marketing\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina - SAFRAS &amp; Mercado","og_description":"\u00bfPor qu\u00e9 es importante entender el balance de la industria del crushing en Argentina? Comprender la din\u00e1mica de la comercializaci\u00f3n de poroto de soja en Argentina implica analizar mucho m\u00e1s que los precios o los m\u00e1rgenes de los productores. Uno de los actores clave \u2014quiz\u00e1s el m\u00e1s influyente en t\u00e9rminos de demanda local\u2014 es la [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-06-26T14:34:54+00:00","og_image":[{"width":600,"height":390,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png","type":"image\/png"}],"author":"sf_marketing","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sf_marketing","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/"},"author":{"name":"sf_marketing","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/87ac33b48b170206d2f791adee2372da"},"headline":"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina","datePublished":"2025-06-26T14:34:54+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/"},"wordCount":1015,"commentCount":371,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png","keywords":["ARGENTINA","Soja"],"articleSection":["Blog Latam"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/","url":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/","name":"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png","datePublished":"2025-06-26T14:34:54+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/06\/Blog-Safras-Latam-695-x-390-px-600-x-390-px-1.png","width":600,"height":390,"caption":"Blog Safras Latam (695 x 390 px) (600 x 390 px) (1)"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/el-balance-del-crushing-una-clave-para-entender-la-comercializacion-de-soja-en-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"El balance del crushing: una clave para entender la comercializaci\u00f3n de soja en Argentina"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/87ac33b48b170206d2f791adee2372da","name":"sf_marketing","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3e3927af6a747068b3907194947e6103dba748c72f497746d7fc79d693a247b6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3e3927af6a747068b3907194947e6103dba748c72f497746d7fc79d693a247b6?s=96&d=mm&r=g","caption":"sf_marketing"},"url":"https:\/\/safras.com.br\/es\/author\/sf_marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=65951"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65951\/revisions"}],"predecessor-version":[{"id":65953,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65951\/revisions\/65953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/65952"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=65951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=65951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=65951"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=65951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}