{"id":65484,"date":"2025-05-15T11:46:02","date_gmt":"2025-05-15T14:46:02","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=65484"},"modified":"2025-05-15T11:46:02","modified_gmt":"2025-05-15T14:46:02","slug":"bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/","title":{"rendered":"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os"},"content":{"rendered":"<p>La Bolsa de Comercio de Rosario (BCR) de cara a la campa\u00f1a 2025\/26, proyecta una siembra hist\u00f3rica de 7,2 millones de hect\u00e1reas, la mayor en 15 a\u00f1os. Este incremento del 4% interanual ser\u00eda impulsado por la notable mejora en las reservas h\u00eddricas entre febrero y abril, que actualmente superan incluso las de a\u00f1os muy favorables como 2021.<\/p>\n<p>Si se alcanzara un rinde promedio de 30,5 qq\/ha y se descontaran 300.000 hect\u00e1reas no cosechadas, la producci\u00f3n estimada para ese ciclo alcanzar\u00eda las 21 millones de toneladas.<\/p>\n<p>Adem\u00e1s del contexto h\u00eddrico favorable, las proyecciones clim\u00e1ticas indican lluvias normales o superiores a lo habitual hasta noviembre. A esto se suman precios accesibles para la urea, insumo clave para el cereal. No obstante, se advierte que ser\u00e1 necesario invertir en tecnolog\u00eda para asegurar buenos resultados, especialmente en campos alquilados, donde los rindes de indiferencia son altos.<\/p>\n<p>\u00abAunque todav\u00eda hay decisiones por tomar y la cosecha actual no ha finalizado, los relevamientos indican que muchos productores planean apostar m\u00e1s fuerte por el trigo en el pr\u00f3ximo ciclo\u00bb, concluye la Gu\u00eda Estrat\u00e9gica para el Agro de la BCR.<\/p>\n<p>En tanto, sobre la campa\u00f1a anterior 2024\/25, a partir de ajustes en el \u00e1rea sembrada por trabajos satelitales que se hicieron en la regi\u00f3n n\u00facleo, se estima la superficie implantada 2024\/25 en 6,91 M ha, tras haber incorporado 227.000 ha. Con un rinde promedio nacional en 30,4 qq\/ha, la producci\u00f3n de trigo 2024\/25 es estimada en 20,1 Mt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Bolsa de Comercio de Rosario (BCR) de cara a la campa\u00f1a 2025\/26, proyecta una siembra hist\u00f3rica de 7,2 millones de hect\u00e1reas, la mayor en 15 a\u00f1os. Este incremento del 4% interanual ser\u00eda impulsado por la notable mejora en las reservas h\u00eddricas entre febrero y abril, que actualmente superan incluso las de a\u00f1os muy favorables [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":58456,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[267],"tags":[],"commodity":[],"class_list":["post-65484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"La Bolsa de Comercio de Rosario (BCR) de cara a la campa\u00f1a 2025\/26, proyecta una siembra hist\u00f3rica de 7,2 millones de hect\u00e1reas, la mayor en 15 a\u00f1os. Este incremento del 4% interanual ser\u00eda impulsado por la notable mejora en las reservas h\u00eddricas entre febrero y abril, que actualmente superan incluso las de a\u00f1os muy favorables [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T14:46:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Horacio Vera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Horacio Vera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/\"},\"author\":{\"name\":\"Horacio Vera\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\"},\"headline\":\"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os\",\"datePublished\":\"2025-05-15T14:46:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/\"},\"wordCount\":264,\"commentCount\":370,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg\",\"articleSection\":[\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/\",\"url\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/\",\"name\":\"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg\",\"datePublished\":\"2025-05-15T14:46:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg\",\"width\":640,\"height\":426,\"caption\":\"campos de trigo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\",\"name\":\"Horacio Vera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"caption\":\"Horacio Vera\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_horacio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/","og_locale":"es_ES","og_type":"article","og_title":"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os - SAFRAS &amp; Mercado","og_description":"La Bolsa de Comercio de Rosario (BCR) de cara a la campa\u00f1a 2025\/26, proyecta una siembra hist\u00f3rica de 7,2 millones de hect\u00e1reas, la mayor en 15 a\u00f1os. Este incremento del 4% interanual ser\u00eda impulsado por la notable mejora en las reservas h\u00eddricas entre febrero y abril, que actualmente superan incluso las de a\u00f1os muy favorables [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-05-15T14:46:02+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg","type":"image\/jpeg"}],"author":"Horacio Vera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Horacio Vera","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/"},"author":{"name":"Horacio Vera","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747"},"headline":"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os","datePublished":"2025-05-15T14:46:02+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/"},"wordCount":264,"commentCount":370,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg","articleSection":["Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/","url":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/","name":"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg","datePublished":"2025-05-15T14:46:02+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/01\/campos-de-trigo.jpg","width":640,"height":426,"caption":"campos de trigo"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/bolsa-de-rosario-estima-siembra-25-26-de-trigo-en-72-mha-la-mayor-en-15-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Bolsa de Rosario estima siembra 25\/26 de trigo en 7,2 Mha, la mayor en 15 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747","name":"Horacio Vera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","caption":"Horacio Vera"},"url":"https:\/\/safras.com.br\/es\/author\/sf_horacio\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=65484"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65484\/revisions"}],"predecessor-version":[{"id":65485,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65484\/revisions\/65485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/58456"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=65484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=65484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=65484"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=65484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}