{"id":65392,"date":"2025-05-07T11:35:16","date_gmt":"2025-05-07T14:35:16","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=65392"},"modified":"2025-05-07T11:35:16","modified_gmt":"2025-05-07T14:35:16","slug":"argentina-elimina-retenciones-a-88-de-productos-industriales-exportables","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/","title":{"rendered":"Argentina elimina retenciones a 88% de productos industriales exportables"},"content":{"rendered":"<p>El gobierno nacional oficializ\u00f3 la eliminaci\u00f3n de retenciones para el 88% de los productos industriales exportables, lo que representa un alivio fiscal significativo para unas 3.600 empresas, mayoritariamente pymes.<\/p>\n<p>&nbsp;<\/p>\n<p>La medida, instrumentada mediante el Decreto 305\/25, exime del pago de entre un 3% y 4,5% en derechos de exportaci\u00f3n a 4.411 posiciones arancelarias, con el objetivo de fomentar la producci\u00f3n y mejorar la competitividad internacional de la industria nacional.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre los sectores beneficiados se destacan maquinaria agr\u00edcola, autopartes, farmac\u00e9utica, cosm\u00e9tica, insecticidas, partes de motores, pl\u00e1sticos, metales y relojer\u00eda. En 2024, estos productos generaron exportaciones por m\u00e1s de US$ 3.800 millones. Sin embargo, la medida excluye a sectores estrat\u00e9gicos como insumos b\u00e1sicos (hierro, acero, aluminio, petroqu\u00edmica) y a la industria automotriz, que seguir\u00e1n tributando.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno nacional oficializ\u00f3 la eliminaci\u00f3n de retenciones para el 88% de los productos industriales exportables, lo que representa un alivio fiscal significativo para unas 3.600 empresas, mayoritariamente pymes. &nbsp; La medida, instrumentada mediante el Decreto 305\/25, exime del pago de entre un 3% y 4,5% en derechos de exportaci\u00f3n a 4.411 posiciones arancelarias, con [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":65393,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[267],"tags":[],"commodity":[],"class_list":["post-65392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Argentina elimina retenciones a 88% de productos industriales exportables - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Argentina elimina retenciones a 88% de productos industriales exportables - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"El gobierno nacional oficializ\u00f3 la eliminaci\u00f3n de retenciones para el 88% de los productos industriales exportables, lo que representa un alivio fiscal significativo para unas 3.600 empresas, mayoritariamente pymes. &nbsp; La medida, instrumentada mediante el Decreto 305\/25, exime del pago de entre un 3% y 4,5% en derechos de exportaci\u00f3n a 4.411 posiciones arancelarias, con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-07T14:35:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Horacio Vera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Horacio Vera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/\"},\"author\":{\"name\":\"Horacio Vera\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\"},\"headline\":\"Argentina elimina retenciones a 88% de productos industriales exportables\",\"datePublished\":\"2025-05-07T14:35:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/\"},\"wordCount\":139,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg\",\"articleSection\":[\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/\",\"url\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/\",\"name\":\"Argentina elimina retenciones a 88% de productos industriales exportables - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg\",\"datePublished\":\"2025-05-07T14:35:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg\",\"width\":1599,\"height\":1200,\"caption\":\"maquinaria1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Argentina elimina retenciones a 88% de productos industriales exportables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747\",\"name\":\"Horacio Vera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g\",\"caption\":\"Horacio Vera\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_horacio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Argentina elimina retenciones a 88% de productos industriales exportables - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/","og_locale":"es_ES","og_type":"article","og_title":"Argentina elimina retenciones a 88% de productos industriales exportables - SAFRAS &amp; Mercado","og_description":"El gobierno nacional oficializ\u00f3 la eliminaci\u00f3n de retenciones para el 88% de los productos industriales exportables, lo que representa un alivio fiscal significativo para unas 3.600 empresas, mayoritariamente pymes. &nbsp; La medida, instrumentada mediante el Decreto 305\/25, exime del pago de entre un 3% y 4,5% en derechos de exportaci\u00f3n a 4.411 posiciones arancelarias, con [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-05-07T14:35:16+00:00","og_image":[{"width":1599,"height":1200,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg","type":"image\/jpeg"}],"author":"Horacio Vera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Horacio Vera","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/"},"author":{"name":"Horacio Vera","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747"},"headline":"Argentina elimina retenciones a 88% de productos industriales exportables","datePublished":"2025-05-07T14:35:16+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/"},"wordCount":139,"commentCount":2,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg","articleSection":["Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/","url":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/","name":"Argentina elimina retenciones a 88% de productos industriales exportables - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg","datePublished":"2025-05-07T14:35:16+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2025\/05\/maquinaria1.jpg","width":1599,"height":1200,"caption":"maquinaria1"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/argentina-elimina-retenciones-a-88-de-productos-industriales-exportables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"Argentina elimina retenciones a 88% de productos industriales exportables"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/8a6e0df178260e340253292bf04da747","name":"Horacio Vera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc30669cd90fb2e21304f48bfae82357e2f9224933e78600478745d017747a8f?s=96&d=mm&r=g","caption":"Horacio Vera"},"url":"https:\/\/safras.com.br\/es\/author\/sf_horacio\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=65392"}],"version-history":[{"count":1,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65392\/revisions"}],"predecessor-version":[{"id":65394,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65392\/revisions\/65394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/65393"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=65392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=65392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=65392"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=65392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}