{"id":65267,"date":"2025-04-23T11:44:38","date_gmt":"2025-04-23T14:44:38","guid":{"rendered":"https:\/\/safras.com.br\/es\/?p=65267"},"modified":"2025-04-23T11:45:04","modified_gmt":"2025-04-23T14:45:04","slug":"la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba","status":"publish","type":"post","link":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/","title":{"rendered":"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz &#8211; BCCBA"},"content":{"rendered":"<p>La provincia de La Pampa se encamina a una producci\u00f3n r\u00e9cord de ma\u00edz con una estimaci\u00f3n de 4.096.300 toneladas, lo que indicar\u00eda un alza del 10% ante la campa\u00f1a anterior y el mayor volumen de las \u00faltimas seis campa\u00f1as, indic\u00f3 la Bolsa de Cereales de C\u00f3rdoba (BCCBA).<\/p>\n<p>Seg\u00fan la primera estimaci\u00f3n de la entidad, la siembra alcanza las 813.600 hect\u00e1reas de las cuales 710.700 son cosechales. El rendimiento se estima en 57,6 qq por hect\u00e1rea.<\/p>\n<p>Sobre el estado, los cultivos sufrieron del estr\u00e9s h\u00eddrico y t\u00e9rmico durante enero, en especial el ma\u00edz temprano. Si bien las recientes lluvias promovieron una recuperaci\u00f3n, se esperan mermas en el rendimiento, sobre todo en los lotes que transitaron su per\u00edodo cr\u00edtico bajo condiciones adversas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La provincia de La Pampa se encamina a una producci\u00f3n r\u00e9cord de ma\u00edz con una estimaci\u00f3n de 4.096.300 toneladas, lo que indicar\u00eda un alza del 10% ante la campa\u00f1a anterior y el mayor volumen de las \u00faltimas seis campa\u00f1as, indic\u00f3 la Bolsa de Cereales de C\u00f3rdoba (BCCBA). Seg\u00fan la primera estimaci\u00f3n de la entidad, la [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":62930,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[267],"tags":[329],"commodity":[46],"class_list":["post-65267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agronegocio-es","tag-maiz-es","commodity-maiz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz - BCCBA - SAFRAS &amp; Mercado<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz - BCCBA - SAFRAS &amp; Mercado\" \/>\n<meta property=\"og:description\" content=\"La provincia de La Pampa se encamina a una producci\u00f3n r\u00e9cord de ma\u00edz con una estimaci\u00f3n de 4.096.300 toneladas, lo que indicar\u00eda un alza del 10% ante la campa\u00f1a anterior y el mayor volumen de las \u00faltimas seis campa\u00f1as, indic\u00f3 la Bolsa de Cereales de C\u00f3rdoba (BCCBA). Seg\u00fan la primera estimaci\u00f3n de la entidad, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/\" \/>\n<meta property=\"og:site_name\" content=\"SAFRAS &amp; Mercado\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T14:44:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T14:45:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"636\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Julieta Marino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Julieta Marino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/\"},\"author\":{\"name\":\"Julieta Marino\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\"},\"headline\":\"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz &#8211; BCCBA\",\"datePublished\":\"2025-04-23T14:44:38+00:00\",\"dateModified\":\"2025-04-23T14:45:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/\"},\"wordCount\":148,\"commentCount\":70,\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg\",\"keywords\":[\"ma\u00edz\"],\"articleSection\":[\"Noticias Agronegocio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/\",\"url\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/\",\"name\":\"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz - BCCBA - SAFRAS &amp; Mercado\",\"isPartOf\":{\"@id\":\"https:\/\/safras.com.br\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg\",\"datePublished\":\"2025-04-23T14:44:38+00:00\",\"dateModified\":\"2025-04-23T14:45:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#primaryimage\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg\",\"width\":960,\"height\":636,\"caption\":\"Ma\u00edz - Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/safras.com.br\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz &#8211; BCCBA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/safras.com.br\/es\/#website\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"name\":\"SAFRAS & Mercado\",\"description\":\"El ecosistema de agronegocios\",\"publisher\":{\"@id\":\"https:\/\/safras.com.br\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/safras.com.br\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/safras.com.br\/es\/#organization\",\"name\":\"SAFRAS & Mercado\",\"url\":\"https:\/\/safras.com.br\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"contentUrl\":\"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"SAFRAS & Mercado\"},\"image\":{\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774\",\"name\":\"Julieta Marino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g\",\"caption\":\"Julieta Marino\"},\"url\":\"https:\/\/safras.com.br\/es\/author\/sf_julieta\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz - BCCBA - SAFRAS &amp; Mercado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/","og_locale":"es_ES","og_type":"article","og_title":"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz - BCCBA - SAFRAS &amp; Mercado","og_description":"La provincia de La Pampa se encamina a una producci\u00f3n r\u00e9cord de ma\u00edz con una estimaci\u00f3n de 4.096.300 toneladas, lo que indicar\u00eda un alza del 10% ante la campa\u00f1a anterior y el mayor volumen de las \u00faltimas seis campa\u00f1as, indic\u00f3 la Bolsa de Cereales de C\u00f3rdoba (BCCBA). Seg\u00fan la primera estimaci\u00f3n de la entidad, la [&hellip;]","og_url":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/","og_site_name":"SAFRAS &amp; Mercado","article_published_time":"2025-04-23T14:44:38+00:00","article_modified_time":"2025-04-23T14:45:04+00:00","og_image":[{"width":960,"height":636,"url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg","type":"image\/jpeg"}],"author":"Julieta Marino","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Julieta Marino","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#article","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/"},"author":{"name":"Julieta Marino","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774"},"headline":"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz &#8211; BCCBA","datePublished":"2025-04-23T14:44:38+00:00","dateModified":"2025-04-23T14:45:04+00:00","mainEntityOfPage":{"@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/"},"wordCount":148,"commentCount":70,"publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"image":{"@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg","keywords":["ma\u00edz"],"articleSection":["Noticias Agronegocio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/","url":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/","name":"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz - BCCBA - SAFRAS &amp; Mercado","isPartOf":{"@id":"https:\/\/safras.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#primaryimage"},"image":{"@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#primaryimage"},"thumbnailUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg","datePublished":"2025-04-23T14:44:38+00:00","dateModified":"2025-04-23T14:45:04+00:00","breadcrumb":{"@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#primaryimage","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2024\/06\/maiz-11.jpg","width":960,"height":636,"caption":"Ma\u00edz - Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/safras.com.br\/es\/la-pampa-se-encamina-a-produccion-record-con-mas-de-4-mi-ton-estimadas-bccba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/safras.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"La Pampa se encamina a producci\u00f3n r\u00e9cord de ma\u00edz &#8211; BCCBA"}]},{"@type":"WebSite","@id":"https:\/\/safras.com.br\/es\/#website","url":"https:\/\/safras.com.br\/es\/","name":"SAFRAS & Mercado","description":"El ecosistema de agronegocios","publisher":{"@id":"https:\/\/safras.com.br\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/safras.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/safras.com.br\/es\/#organization","name":"SAFRAS & Mercado","url":"https:\/\/safras.com.br\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/","url":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","contentUrl":"https:\/\/safras.com.br\/es\/wp-content\/uploads\/2023\/01\/cropped-favicon.png","width":512,"height":512,"caption":"SAFRAS & Mercado"},"image":{"@id":"https:\/\/safras.com.br\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/3416d9a13f71584c19d44af415b80774","name":"Julieta Marino","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/safras.com.br\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/edb9a909cb969bf70267c5bad4733db348b286011e3a47666fcbe2263cd5c089?s=96&d=mm&r=g","caption":"Julieta Marino"},"url":"https:\/\/safras.com.br\/es\/author\/sf_julieta\/"}]}},"_links":{"self":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/comments?post=65267"}],"version-history":[{"count":2,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65267\/revisions"}],"predecessor-version":[{"id":65269,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/posts\/65267\/revisions\/65269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media\/62930"}],"wp:attachment":[{"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/media?parent=65267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/categories?post=65267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/tags?post=65267"},{"taxonomy":"commodity","embeddable":true,"href":"https:\/\/safras.com.br\/es\/wp-json\/wp\/v2\/commodity?post=65267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}